{"id":39144,"date":"2026-04-28T09:53:01","date_gmt":"2026-04-28T09:53:01","guid":{"rendered":"https:\/\/sviluppodunp.it\/martingale\/?post_type=approfondimento&#038;p=39144"},"modified":"2026-04-28T09:55:13","modified_gmt":"2026-04-28T09:55:13","slug":"sns-reaal-n-v-e-sns-bank-n-v","status":"publish","type":"approfondimento","link":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/","title":{"rendered":"SNS REAAL N.V. e SNS Bank N.V."},"content":{"rendered":"<p>Martingale Risk supporta gli investitori nei bond subordinati Sns Reaal e Sns Bank nel recupero delle perdite nei confronti della societ\u00e0 emittente promuovendo un\u2019<strong>azione collettiva\u00a0<\/strong>al fine di far ottenere il giusto risarcimento. Le azioni di Martingale non prevedono costi anticipati (<em>No Win, No Fee<\/em>). Previa analisi gratuita della posizione, Martingale Risk finanzia completamente la tua causa, permettendoti di ottenere un risarcimento senza alcun rischio o costo iniziale.<\/p>\n<p><strong>SNS REAAL N.V.<\/strong>\u00a0e la collegata\u00a0<strong>SNS Bank N.V.<\/strong>\u00a0(di seguito, \u201cSNS\u201d) sono state due compagnie olandesi attive nel ramo bancario e assicurativo.\u00a0Negli anni antecedenti al 2013, SNS si \u00e8 ripetutamente trovata in uno status di difficolt\u00e0 finanziaria, innescato principalmente da imponenti\u00a0<strong>perdite accumulate nel tempo dall\u2019ampio portafoglio di prestiti immobiliari creato dalla collegata SNS Property Finance<\/strong>. Questa divisione aveva infatti accumulato un\u2019enorme esposizione su numerosissimi prestiti immobiliari ad alto rischio che, una volta deteriorati, hanno causato una carenza di capitale (shortfall) e conseguente instabilit\u00e0 finanziaria.<\/p>\n<p>Nonostante numerosi tentativi di ristrutturazione e di apporto di capitale, il peggioramento della situazione ha fatto s\u00ec che il 1\u00b0 febbraio 2013, per scongiurare un potenziale collasso che avrebbe potuto destabilizzare l\u2019intero sistema finanziario olandese, il Governo \u00e8 intervenuto nazionalizzando SNS REAAL N.V. e SNS Bank N.V., iniettando 3,7 miliardi di euro di capitale e assumendone il controllo al fine di stabilizzare gli istituti, proteggere i clienti olandesi e ripristinare la fiducia nel settore bancario locale.<\/p>\n<p>A seguito della nazionalizzazione, il 1\u00b0 febbraio 2013 il governo olandese ha espropriato alcune obbligazioni e altri componenti di capitale emessi da SNS, provocando cos\u00ec il crollo dei prezzi di questi strumenti (cfr. elenco a fondo pagina).<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-34481\" src=\"https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-1024x455.png\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-200x89.png 200w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-300x133.png 300w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-400x178.png 400w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-600x266.png 600w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-768x341.png 768w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-800x355.png 800w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-1024x455.png 1024w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-1200x533.png 1200w, https:\/\/martingalerisk.it\/wp-content\/uploads\/2024\/06\/Progetto-senza-titolo-1-1-1536x682.png 1536w\" alt=\"Grafico Sns Bank\" width=\"1024\" height=\"455\" \/><figcaption class=\"wp-element-caption\">Grafico Sns Bank<\/figcaption><\/figure>\n<p><strong>Il 21 aprile 2023 la Corte Suprema olandese ha ratificato una Sentenza del 2021 della Camera di Commercio della Corte d\u2019Appello di Amsterdam, che prevedeva il diritto di risarcimento per i possessori degli strumenti espropriati di SNS<\/strong>. Dopo anni di procedimenti legali,\u00a0<strong>il Ministero delle Finanze olandese ha approvato un piano di indennizzo di quasi 804,81 milioni di Euro con interessi da distribuire agli aventi diritto<\/strong>.<\/p>\n<p>Secondo tale piano,\u00a0<strong>i possessori dei titoli SNS espropriati indicati qui di seguito hanno diritto ad un ristoro del danno subito<\/strong>:<\/p>\n<ul class=\"wp-block-list\">\n<li>detentori di\u00a0<strong>obbligazioni subordinate emesse da SNS Bank o SNS REAAL<\/strong>, possedute al 1\u00b0 marzo 2013 e non successivamente cedute;<\/li>\n<li>detentori di uno o pi\u00f9\u00a0<strong>crediti litigiosi ottenuti da un\u2019altra persona o organizzazione che deteneva obbligazioni subordinate di SNS REAAL o SNS Bank<\/strong>\u00a0al 1\u00b0 marzo 2013;<\/li>\n<li>detentori di\u00a0<strong>obbligazioni subordinate non quotate<\/strong>, emessa da SNS Bank con il nome \u201c<strong>SNS Participatie Certificaten 3<\/strong>\u201d al 1\u00b0 marzo 2013 che non hanno ancora ricevuto alcun indennizzo da SNS Bank o che comunque non hanno ottenuto un ristoro superiore al 90% del capitale investito;<\/li>\n<li>detentori di uno o pi\u00f9\u00a0<strong>crediti litigiosi ottenuti da un\u2019altra persona o organizzazione che deteneva obbligazioni subordinate non quotate<\/strong>, emesse da SNS Bank con il nome \u201cSNS Participatie Certificaten 3\u201d;<\/li>\n<li>detentori dei seguenti\u00a0<strong>prestiti emessi da SNS REAAL<\/strong>:\n<ul class=\"wp-block-list\">\n<li>il prestito\u00a0<strong>Van Doorn<\/strong>\u00a0del 2000-2020 (7,13%);<\/li>\n<li>il prestito\u00a0<strong>Van Doorn<\/strong>\u00a0del 2000-2020 (7,10%);<\/li>\n<li>il prestito\u00a0<strong>Stichting\u00a0<\/strong>del 1997-2014;<\/li>\n<li>il prestito\u00a0<strong>Poseidon\u00a0<\/strong>del 1999-2019;<\/li>\n<li>il prestito\u00a0<strong>OHRA Stichting<\/strong>\u00a0del 1999-2024.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color has-large-font-size wp-elements-b4ca076a7b3ac5a6b630fdf32a0390f7 fusion-responsive-typography-calculated\" data-fontsize=\"21\" data-lineheight=\"33.6px\">Perch\u00e8 rivolgersi a Martingale Risk per il recupero delle perdite su titoli SNS Bank<\/h3>\n<p>La\u00a0<strong>procedura di richiesta di risarcimento<\/strong>\u00a0per i danni subiti andr\u00e0 presentata in\u00a0<strong>Olanda<\/strong>, pu\u00f2 risultare impegnativa e richieder\u00e0 competenze specializzate.\u00a0<strong>Affidandovi alla Martingale Risk potrete sfruttare la nostra vasta esperienza e le nostre conoscenze specialistiche<\/strong>,\u00a0<strong>senza costi<\/strong>\u00a0o\u00a0<strong>commissioni<\/strong>\u00a0<strong>iniziali<\/strong>\u00a0e\u00a0<strong>senza non correre alcun rischio<\/strong>: veniamo pagati\u00a0<strong>solo a recupero avvenuto, con una percentuale sull\u2019importo recuperato<\/strong>.<\/p>\n","protected":false},"featured_media":39146,"template":"","meta":{"_acf_changed":false},"categoria-approfondimento":[339],"class_list":["post-39144","approfondimento","type-approfondimento","status-publish","has-post-thumbnail","hentry","categoria-approfondimento-azioni-collettive"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SNS REAAL N.V. e SNS Bank N.V. - Martingale<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SNS REAAL N.V. e SNS Bank N.V. - Martingale\" \/>\n<meta property=\"og:description\" content=\"Martingale Risk supporta gli investitori nei bond subordinati Sns Reaal [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T09:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-28-115102.png\" \/>\n\t<meta property=\"og:image:width\" content=\"677\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/\",\"name\":\"SNS REAAL N.V. e SNS Bank N.V. - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Screenshot-2026-04-28-115102.png\",\"datePublished\":\"2026-04-28T09:53:01+00:00\",\"dateModified\":\"2026-04-28T09:55:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Screenshot-2026-04-28-115102.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Screenshot-2026-04-28-115102.png\",\"width\":677,\"height\":568,\"caption\":\"Sns\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/sns-reaal-n-v-e-sns-bank-n-v\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SNS REAAL N.V. e SNS Bank N.V.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SNS REAAL N.V. e SNS Bank N.V. - Martingale","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"SNS REAAL N.V. e SNS Bank N.V. - Martingale","og_description":"Martingale Risk supporta gli investitori nei bond subordinati Sns Reaal [...]","og_url":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/","og_site_name":"Martingale","article_modified_time":"2026-04-28T09:55:13+00:00","og_image":[{"width":677,"height":568,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-28-115102.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/","url":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/","name":"SNS REAAL N.V. e SNS Bank N.V. - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-28-115102.png","datePublished":"2026-04-28T09:53:01+00:00","dateModified":"2026-04-28T09:55:13+00:00","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-28-115102.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-28-115102.png","width":677,"height":568,"caption":"Sns"},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/sns-reaal-n-v-e-sns-bank-n-v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"SNS REAAL N.V. e SNS Bank N.V."}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/approfondimento\/39144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/approfondimento"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/approfondimento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/39146"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=39144"}],"wp:term":[{"taxonomy":"categoria-approfondimento","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categoria-approfondimento?post=39144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}