{"id":877,"date":"2024-09-10T16:02:46","date_gmt":"2024-09-10T16:02:46","guid":{"rendered":"https:\/\/sviluppodunp.it\/martingale\/?post_type=approfondimento&#038;p=877"},"modified":"2026-04-16T10:51:39","modified_gmt":"2026-04-16T10:51:39","slug":"fondi-h2o","status":"publish","type":"approfondimento","link":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/","title":{"rendered":"Fondi  H2O"},"content":{"rendered":"<p><strong>Scopri come recuperare senza costi anticipati<\/strong> Martingale Risk sta promuovendo\u00a0<strong>un\u2019azione collettiva<\/strong>\u00a0<strong>contro tutti gli intermediari finanziari che hanno consigliato o lasciato che i propri clienti investissero in titoli di assoluto rischio quali i Fondi H2O<\/strong>, finendo cos\u00ec per perdere tutti i propri risparmi. Previa\u00a0<strong>analisi gratuita\u00a0<\/strong>della posizione, Martingale Risk verificher\u00e0 eventuali violazioni da parte delle banche intermediarie degli obblighi informativi previsti dalla legge italiana (Codice Civile, Testo Unico della Finanza e Regolamenti Consob) e da quella europea (Direttiva MiFID).\u00a0<strong>Recuperare le perdite da un investimento in Fondi H2O oggi \u00e8 possibile<\/strong>. <strong>Cronistoria del crollo dei Fondi H2O<\/strong> H2O \u00e8 una societ\u00e0 di gestione fondata nel 2010 da Bruno Crastes.\u00a0 La societ\u00e0 ha sede a Londra, investiva nei mercati obbligazionari, azionari e valutari a livello globale ed era partecipata in forma maggioritaria da Naxitis, una banca d\u2019affari francese. La societ\u00e0 \u00e8 cresciuta rapidamente passando dalla gestione di circa 3 miliardi di Euro di\u00a0<em>asset<\/em>\u00a0(2013) a oltre 30 mld di Euro in meno di dieci anni. Come verr\u00e0 meglio spiegato qui di seguito, sin dal 2015 H2O ha investito in molteplici societ\u00e0 che hanno emesso strumenti finanziari di natura sostanzialmente illiquida. La H2O, tuttavia, si era impegnata a soddisfare le richieste normativa di cui ai regolamenti UCITS (<em>Undertakings for collective investments in transferable securities<\/em>), le quali consentono un investimento massimo del 10% del\u00a0<em>Net Asset Value\u00a0<\/em>(sostanzialmente, il valore degli attivi del fondo) in valori mobiliari di dubbia liquidabilit\u00e0 (cio\u00e8 non vendibili in tempi certi e\/o senza un forte sconto sul prezzo), al quale si aggiungevano ulteriori limitazioni per gli investimenti aventi come controparte una singola societ\u00e0 di natura non finanziaria. Ripercorrendo le tappe principali della vicenda H2O, nel giugno 2019 il\u00a0<em>Financial Times<\/em>\u00a0ha pubblicato un articolo che parlava di un investimento di\u00a0<strong>oltre 1,4 miliardi di euro<\/strong>\u00a0in\u00a0<strong>bond potenzialmente illiquidi<\/strong>\u00a0fonte di finanziamento di alcune societ\u00e0 tutte riconducibili, con annesso rischio di controparte, all\u2019imprenditore tedesco Lars Windhorst. Si fa presente che il fondatore della H2O Asset Management, Bruno Crastes, figurava nell\u2019<em>advisory board\u00a0<\/em>di una societ\u00e0 collegata allo stesso Windhorst, in evidente conflitto d\u2019interesse. In un successivo report del 3 aprile 2020 gli analisti di Morningstar hanno assegnato un\u00a0<em>rating<\/em>\u00a0\u201c<em>Negative<\/em>\u201d al fondo \u201cH2O Allegro\u201d in virt\u00f9 della pesante esposizione in\u00a0<em>corporate\u00a0<\/em>bond illiquidi collegati al sopracitato finanziere Lars Windhorst. Il peso di questi rischiosissimi investimenti, rispetto al NAV del fondo, ha pertanto infranto le regole sulla concentrazione del rischio di controparte. Oltre al gi\u00e0 citato fondo \u201c<strong>H2O Allegro<\/strong>\u201d, altri cinque Fondi H2O hanno sottoscritto obbligazioni illiquide per quote di assoluta rilevanza del rispettivo NAV: \u201c<strong>H2O Adagio<\/strong>\u201d, \u201c<strong>H2O Moderato<\/strong>\u201d, \u201c<strong>H2O MultiBonds<\/strong>\u201d, \u201c<strong>H2O MultiStrategies<\/strong>\u201d e \u201c<strong>H2O Vivace<\/strong>\u201d.<\/p>\r\n<!-- \/wp:post-content -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Martingale Risk\u00a0segue da ormai 14 anni casistiche di perdite come quelle da Fondi H2O, sia a livello nazionale che internazionale.\u00a0<strong>Anche in questa occasione \u00e8 al fianco dei risparmiatori danneggiati, permettendo loro di avviare un\u2019efficace azione risarcitoria volta a recuperare le somme perse<\/strong>. <strong>Il crollo dei Fondi H2O<\/strong> Il crollo del valore dei Fondi H2O comincia nel febbraio del 2020 quando, in un solo mese, sono andati bruciati circa 7 miliardi di Euro. Tale andamento di mercato, dopo i primi interrogativi espressi dai professionisti di settore a met\u00e0 2019, \u00e8 dunque l\u2019esplicitazione dell\u2019indebita assunzione di enormi rischi negli investimenti operati dalla societ\u00e0 H2O Asset Management, che come detto aveva caricato gli attivi dei Fondi H2O di quote assolutamente elevate di obbligazioni societarie di natura sostanzialmente illiquida e con un elevatissimo rischio emittente.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Nell\u2019odierna vicenda l\u2019Italia ha rappresentato uno dei principali mercati di sbocco per il collocamento dei Fondi H2O da parte di\u00a0<strong>oltre 30 intermediari italiani<\/strong>, per un importo stimato di circa il 30% dei poco pi\u00f9 di 5 miliardi di Euro.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>La mancanza di liquidit\u00e0 e altre gravi anomalie nella gestione del rischio, hanno spinto l\u2019Autorit\u00e9 des march\u00e9s financiers (la Consob francese), in data\u00a0<strong>28\/08\/2020<\/strong>\u00a0a sospendere i seguenti fondi:<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:list -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\r\n<li>H2O MultiBonds,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H2O Allegro,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H2O MultiStrategies.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item --><!-- \/wp:list -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>In seguito, la societ\u00e0 ha deciso di sospendere la commercializzazione di ulteriori cinque fondi:<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:list -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\r\n<li>H2O Adagio,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H2O Moderato,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H2O Vivace,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H2O MultiEquities,<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item -->\r\n\r\n<!-- wp:list-item -->\r\n<ul class=\"wp-block-list\">\r\n<li style=\"list-style-type: none;\">\r\n<ul class=\"wp-block-list\">\r\n<li>H20 Deep Value.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n<!-- \/wp:list-item --><!-- \/wp:list -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Come ben visibile nel grafico esemplificativo che qui segue, successivamente al drastico crollo di cui si \u00e8 parlato sopra il valore dei Fondi H2O non \u00e8 pi\u00f9 tornato sui livelli pre-crisi. Come certificato dagli stessi dati presenti sul sito della H2O Asset Management, a titolo di esempio, il fondo \u201cH2O ADAGIO SP R\u201d (ISIN: FR0013534898) ha perso oltre il 95% del proprio valore negli ultimi 3 anni. <img decoding=\"async\" class=\"alignnone size-full wp-image-883\" src=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1.png\" alt=\"\" width=\"1024\" height=\"592\" srcset=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-200x116.png 200w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-300x173.png 300w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-400x231.png 400w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-600x347.png 600w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-768x444.png 768w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1-800x463.png 800w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Fondi-H2O-1024x592-1.png 1024w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <strong>La creazione di Fondi Side Pocket di H2O<\/strong> Resa definitivamente nota l\u2019enorme (indebita) presenza di obbligazioni illiquide tra gli\u00a0<em>asset<\/em>\u00a0dei Fondi H2O con il conseguente crollo del valore delle quote dei fondi (nonch\u00e9 delle masse gestite da H2O, scese da 30 a 16 miliardi di Euro in un solo anno),\u00a0ed essendo avvenuta la sospensione dei fondi interessati da parte delle autorit\u00e0 francesi, ad inizio ottobre 2020 la H2O Asset Management ha fatto ricorso ad un particolare strumento previso dalla normativa francese: i cc.dd.\u00a0<strong>Side Pocket\u00a0<\/strong>(\u201cSP\u201d). Con la creazione di questi ultimi\u00a0<strong>H2O Asset Management ha separato il gruppo degli strumenti finanziari<\/strong>\u00a0detenuti nel fondo originario, dividendoli tra\u00a0<strong>strumenti liquidi\u00a0<\/strong>(contenuti nel cosiddetto fondo \u201creplica\u201d) e\u00a0<strong>strumenti illiquidi\u00a0<\/strong>(contenuti, per l\u2019appunto, nel fondo \u201cSide Pocket\u201d). In data\u00a0<strong>05\/10\/2020\u00a0<\/strong>\u00e8 avvenuto pertanto lo scorporo dei Fondi H2O originari in:<\/p>\r\n<ol class=\"wp-block-list\">\r\n<li><strong><u>Fondi Replica<\/u><\/strong>\u00a0dove sono confluiti gli asset ritenuti liquidi, costruiti secondo una rinnovata strategia che non prevede pi\u00f9 investimenti concentrati in\u00a0<em>strumenti illiquidi come viceversa avvenuto in passato<\/em>.<\/li>\r\n<li><strong><u>Fondi Side Pocket<\/u><\/strong>\u00a0nei quali sono confluiti gli strumenti illiquidi, nella speranza di poter procedere con una loro liquidazione cos\u00ec da restituire poi il ricavato agli investitori. Dopo un iniziale (ottimistico) rimborso previsto entro il 2021, le difficolt\u00e0 incontrate nel dismettere i titoli illiquidi hanno spinto la H2O Asset Management, a fine maggio 2021, a\u00a0rimandare ulteriormente\u00a0la data in cui gli investitori avrebbero potuto ottenere un rimborso dei propri risparmi persi. D\u2019altronde, nel 2023 la societ\u00e0 di revisione KPMG \u2013 nella sua relazione contabile collegata al bilancio del fondo \u201cH2O ADAGIO SP\u201d al 30\/09\/2023 \u2013 ha informato gli investitori di\u00a0<strong>non essere in grado di \u201c<em>esprimere un giudizio sul fatto che il bilancio d\u2019esercizio fornisca, in conformit\u00e0 ai principi contabili francesi, una rappresentazione veritiera e corretta della situazione patrimoniale e finanziaria. principi contabili francesi, una rappresentazione veritiera e corretta della situazione patrimoniale e finanziaria del fondo alla fine del periodo<\/em><\/strong>\u201d<em>.<\/em>\u00a0E ancora: \u201c<em>A causa delle circostanze descritte nelle note al bilancio,\u00a0<strong>non siamo in grado di valutare la natura probatoria dei dati utilizzati e l\u2019adeguatezza del metodo di valutazione delle attivit\u00e0 illiquide nel bilancio di chiusura<\/strong><\/em>\u201d.<\/li>\r\n<\/ol>\r\n<p>Nonostante due iniziative condotte dalla londinese H2O AM LLP e volte al rimborso di parte dei fondi Side Pocket, il valore sostanzialmente nullo dei titoli illiquidi contenuto nei fondi in parola ha fatto s\u00ec che\u00a0<strong><u>migliaia di investitori italiani non abbiano ancora recuperato le somme investite e perse nei Fondi H2O<\/u><\/strong>. <strong>Cosa pu\u00f2 fare un investitore che ha perso soldi investiti sui Fondi H2O?<\/strong> Per i risparmiatori che hanno acquistato i Fondi H2O, la via pi\u00f9 concreta per ottenere il\u00a0<strong>giusto risarcimento<\/strong>\u00a0delle perdite subite consiste nel\u00a0<strong>rivalersi nei confronti delle<\/strong>\u00a0<strong>banche intermediarie<\/strong>\u00a0<strong>che hanno venduto loro questi titoli<\/strong>.\u00a0<strong>Il rischio di un investimento in Fondi H2O<\/strong>, sostanzialmente non rilevabile dal piccolo investitore se non a seguito della sospensione degli stessi dalle quotazioni, viceversa\u00a0<strong>era ben chiaro a operatori professionali, quali tutte le banche intermediarie italiane,<\/strong>\u00a0<strong>le quali \u2013 ci\u00f2 nonostante \u2013 hanno consigliato l\u2019acquisto e\/o lasciato che i propri clienti comprassero i Fondi H2O\u00a0<u>senza informarli dei rischi\u00a0ai quali stavano andando incontro<\/u><\/strong>. Ricordiamo inoltre che\u00a0<strong>gli intermediari hanno altres\u00ec l\u2019obbligo di sottoporre ai propri clienti un\u00a0<u>questionario di profilatura<\/u><\/strong>\u00a0(c.d. questionario MiFID),\u00a0<strong>con l\u2019obiettivo di capire la tipologia di investitore e quindi\u00a0<u>l\u2019idoneit\u00e0<\/u><\/strong>\u00a0(rispetto alle conoscenze\/esperienze\/propensione al rischio\/obiettivi di investimento\/situazione finanziaria e patrimoniale)\u00a0<strong><u>di tale profilo rispetto all\u2019investimento in strumenti finanziari rischiosi quali i Fondi H2O<\/u><\/strong>. Nel condurre tale\u00a0<em>test<\/em>\u00a0(la c.d. valutazione di appropriatezza\/adeguatezza nei termini della normativa), ovviamente l\u2019intermediario non deve in alcun modo indirizzare il cliente verso specifiche risposte n\u00e9, tantomeno, pu\u00f2 sottrarsi ad un\u2019analisi critica sulla veridicit\u00e0 di queste ultime (procedendo ad una nuova profilatura in caso di incoerenze o scarsa affidabilit\u00e0 delle risposte). <strong>Martingale Risk d\u00e0 la possibilit\u00e0 di avvalersi di un\u2019azione risarcitoria contro questi intermediari finanziari che non hanno rispettato gli obblighi informativi previsti dalla legge italiana (Codice Civile, Testo Unico della Finanza e Regolamenti Consob) e da quella europea (Direttiva MiFID), lasciando cos\u00ec colpevolmente che i propri clienti perdessero ingiustamente tutti i propri risparmi<\/strong>. <strong>Fondi H2O: come ottenere un risarcimento?<\/strong> <strong>Ad oggi la soluzione pi\u00f9 immediata e concreta per recuperare le perdite generate dai Fondi H2O \u00e8 quella di agire contro le banche intermediarie che hanno permesso ai clienti di acquistare questi titoli<\/strong>, instaurando una\u00a0<strong>causa civile ordinaria<\/strong>\u00a0o un\u00a0<strong>ricorso ACF<\/strong>\u00a0(Arbitro per le Controversie Finanziarie, presso la Consob) per le responsabilit\u00e0 loro imputabili. Martingale Risk, societ\u00e0 leader nell\u2019ambito del contenzioso bancario, propone\u00a0<strong>un\u2019azione risarcitoria per conto di tutti gli investitori che hanno acquistato i fondi<\/strong>.\u00a0Offriamo una\u00a0<strong>Analisi Preliminare Gratuita<\/strong>\u00a0degli investimenti, con l\u2019obiettivo di valutare senza impegno se e quanto \u00e8 possibile recuperare dalla banca. Inoltre, previa valutazione gratuita e non vincolante, Martingale Risk potr\u00e0 formulare un\u2019offerta a\u00a0<strong>Zero Costi Anticipati<\/strong>: in questo modo,\u00a0<strong>il cliente che ha gi\u00e0 subito perdite economiche non dovr\u00e0 pagare alcuna somma aggiuntiva, ma corrisponder\u00e0 unicamente una percentuale sulle somme recuperate, e solo a risarcimento effettivamente avvenuto<\/strong>. <a href=\"https:\/\/martingalerisk.it\/perdite-da-investimento-su-fondi-h2o\/#formfondih2o\"><strong>Compila il\u00a0<em>form<\/em>\u00a0soprastante<\/strong><\/a>\u00a0per richiedere anche tu un\u2019analisi gratuita e non vincolante del tuo caso, al fine di valutare le possibilit\u00e0 di\u00a0<strong>ottenere un risarcimento per Fondi H2O<\/strong>. <strong>Documenti utili<\/strong><\/p>\r\n<ul>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O ADAGIO SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/1ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Adagio-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O ALLEGRO SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/2ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Allegro-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O MODERATO SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Moderato-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O MULTIBONDS SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Multibonds-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O MULTIEQUITIES SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Multiequities-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O MULTISTRATEGIES SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-Multistrategies-SP.pdf\">clicca qui per scaricare il file<\/a>;<\/li>\r\n<li>Relazione del revisore contabile KPMG sul valore degli asset illiquidi del fondo \u201cH2O VIVACE SP\u201d \u2013 <a href=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/ANNUAL-REPORT-Relazione-KPMG-Settembre-2023-H2O-VIVACE-SP.pdf\">clicca qui per scaricare il file<\/a>.<\/li>\r\n<\/ul>","protected":false},"featured_media":878,"template":"","meta":{"_acf_changed":false},"categoria-approfondimento":[],"class_list":["post-877","approfondimento","type-approfondimento","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fondi H2O - Martingale<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondi H2O - Martingale\" \/>\n<meta property=\"og:description\" content=\"Scopri come recuperare senza costi anticipati Martingale Risk sta promuovendo\u00a0un\u2019azione [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T10:51:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Investimenti-sito-10.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/\",\"name\":\"Fondi H2O - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Investimenti-sito-10.png\",\"datePublished\":\"2024-09-10T16:02:46+00:00\",\"dateModified\":\"2026-04-16T10:51:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Investimenti-sito-10.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Investimenti-sito-10.png\",\"width\":1024,\"height\":683,\"caption\":\"FONDI H2O\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/approfondimento\\\/fondi-h2o\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fondi H2O\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fondi H2O - Martingale","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Fondi H2O - Martingale","og_description":"Scopri come recuperare senza costi anticipati Martingale Risk sta promuovendo\u00a0un\u2019azione [...]","og_url":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/","og_site_name":"Martingale","article_modified_time":"2026-04-16T10:51:39+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Investimenti-sito-10.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/","url":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/","name":"Fondi H2O - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Investimenti-sito-10.png","datePublished":"2024-09-10T16:02:46+00:00","dateModified":"2026-04-16T10:51:39+00:00","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Investimenti-sito-10.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/Investimenti-sito-10.png","width":1024,"height":683,"caption":"FONDI H2O"},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/approfondimento\/fondi-h2o\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"Fondi H2O"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/approfondimento\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/approfondimento"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/approfondimento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/878"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"categoria-approfondimento","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categoria-approfondimento?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}