{"id":25,"date":"2026-03-19T09:52:34","date_gmt":"2026-03-19T09:52:34","guid":{"rendered":"https:\/\/sviluppodunp.it\/martingale\/?page_id=25"},"modified":"2026-05-06T07:39:00","modified_gmt":"2026-05-06T07:39:00","slug":"lavora-con-noi","status":"publish","type":"page","link":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/","title":{"rendered":"Lavora con noi"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:150px;--awb-padding-bottom:150px;--awb-padding-top-small:50px;--awb-padding-bottom-small:50px;--awb-background-image:url(&quot;https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/03\/Group-361-1-1200x334.png&quot;);--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:var(--awb-color2);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:64px;\"><h1 class=\"fusion-title-heading title-heading-left\" style=\"font-family:var(--awb-typography1-font-family);font-weight:var(--awb-typography1-font-weight);font-style:var(--awb-typography1-font-style);margin:0;letter-spacing:var(--awb-typography1-letter-spacing);text-transform:var(--awb-typography1-text-transform);font-size:1em;line-height:var(--awb-typography1-line-height);\">Lavora con noi<\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:75px;--awb-padding-bottom:75px;--awb-padding-top-small:0px;--awb-padding-bottom-small:0px;--awb-background-color:var(--awb-color2);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_5 3_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.2%;--awb-width-medium:60%;--awb-order-medium:0;--awb-spacing-right-medium:3.2%;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n        <link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\">\n    <link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin>\n    <link href=\"https:\/\/fonts.googleapis.com\/css2?family=Inter:wght@400;500;600;700&display=swap\" rel=\"stylesheet\">\n    \n    <style>\n        .mcom-6a046cabdbdaa-wrap {\n            max-width: 1200px !important;\n            margin: 0 auto !important;\n            padding: 0px 0px !important;\n            font-family: 'Inter', sans-serif !important;\n        }\n\n        .mcom-6a046cabdbdaa-wrap .mcom-6a046cabdbdaa-title,\n        .mcom-6a046cabdbdaa-wrap h2.mcom-6a046cabdbdaa-title {\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 700 !important;\n            font-size: 40px !important;\n            line-height: 1.15 !important;\n            color: #1a1a1a !important;\n            margin: 0 0 40px 0 !important;\n            padding: 0 !important;\n            letter-spacing: 0 !important;\n            text-transform: none !important;\n        }\n\n        .mcom-6a046cabdbdaa-list {\n            list-style: none !important;\n            margin: 0 !important;\n            padding: 0 !important;\n            display: flex !important;\n            flex-direction: column !important;\n            gap: 12px !important;\n        }\n\n        .mcom-6a046cabdbdaa-list li {\n            display: flex !important;\n            align-items: flex-start !important;\n            gap: 16px !important;\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 400 !important;\n            font-size: 18px !important;\n            line-height: 1.6 !important;\n            color: #333 !important;\n            margin: 0 !important;\n            padding: 0 !important;\n        }\n\n        .mcom-6a046cabdbdaa-list li strong,\n        .mcom-6a046cabdbdaa-list li b {\n            font-weight: 700 !important;\n            color: #1a1a1a !important;\n            font-size: 18px !important;\n        }\n\n        .mcom-6a046cabdbdaa-arrow {\n            flex-shrink: 0 !important;\n            width: 20px !important;\n            height: 20px !important;\n            margin-top: 5px !important;\n            display: block !important;\n        }\n\n        \/* \u2500\u2500 Responsive \u2500\u2500 *\/\n        @media (max-width: 768px) {\n            .mcom-6a046cabdbdaa-wrap .mcom-6a046cabdbdaa-title,\n            .mcom-6a046cabdbdaa-wrap h2.mcom-6a046cabdbdaa-title {\n                font-size: 28px !important;\n                margin-bottom: 28px !important;\n            }\n            .mcom-6a046cabdbdaa-list li {\n                font-size: 16px !important;\n            }\n            .mcom-6a046cabdbdaa-wrap {\n                padding: 40px 16px !important;\n            }\n        }\n    <\/style>\n\n    <div class=\"mcom-6a046cabdbdaa-wrap\">\n\n        <h2 class=\"mcom-6a046cabdbdaa-title\">Entrare nella Community<br>di Martingale Risk significa:<\/h2>\n\n        <ul class=\"mcom-6a046cabdbdaa-list\">\n            <li>\n                <svg class=\"mcom-6a046cabdbdaa-arrow\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M4 10h12M11 5l5 5-5 5\" stroke=\"#c8102e\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n                <span>Collaborare con una Societ\u00e0 contraddistinta da un'<strong>elevata reputazione sul mercato<\/strong>, dalla seriet\u00e0 e dall'impegno dei propri consulenti.<\/span>\n            <\/li>\n            <li>\n                <svg class=\"mcom-6a046cabdbdaa-arrow\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M4 10h12M11 5l5 5-5 5\" stroke=\"#c8102e\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n                <span>Inserirsi in un <strong>business in forte crescita che offre opportunit\u00e0<\/strong> senza confronti per sviluppo professionale e soddisfazione economica.<\/span>\n            <\/li>\n            <li>\n                <svg class=\"mcom-6a046cabdbdaa-arrow\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M4 10h12M11 5l5 5-5 5\" stroke=\"#c8102e\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n                <span><strong>Aiutare privati e imprese a reagire contro gli illeciti<\/strong> commessi dalle banche e far recuperare loro i soldi sottratti in maniera illegittima.<\/span>\n            <\/li>\n            <li>\n                <svg class=\"mcom-6a046cabdbdaa-arrow\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M4 10h12M11 5l5 5-5 5\" stroke=\"#c8102e\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n                <span>Lavorare per una Societ\u00e0 che vanta un numero impressionante di <strong>casi di successo<\/strong>, collezionati in un'attivit\u00e0 che va avanti da ormai pi\u00f9 di un decennio.<\/span>\n            <\/li>\n        <\/ul>\n\n    <\/div>\n\n    <\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_5 2_5 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/AdobeStock_234092269_Preview-1-4.png&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:40%;--awb-margin-top-large:0px;--awb-spacing-right-large:4.8%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:4.8%;--awb-width-medium:40%;--awb-order-medium:0;--awb-spacing-right-medium:4.8%;--awb-spacing-left-medium:4.8%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2026\/04\/AdobeStock_234092269_Preview-1-4.png\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder\" alt=\"lavora con noi\" aria-label=\"Lavora con noi\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27667%27%20height%3D%27454%27%20viewBox%3D%270%200%20667%20454%27%3E%3Crect%20width%3D%27667%27%20height%3D%27454%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" id=\"candidati-form\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<link href=\"https:\/\/fonts.googleapis.com\/css2?family=DM+Sans:wght@300;400;500;600&display=swap\" rel=\"stylesheet\"\/>\n\n<style>\n.mrj-wrap *, .mrj-wrap *::before, .mrj-wrap *::after {\n    box-sizing: border-box; margin: 0; padding: 0;\n}\n.mrj-wrap {\n    font-family: 'DM Sans', 'Helvetica Neue', sans-serif;\n    background: #000000;\n    color: #ffffff;\n    padding: 80px 0px;\n    display: grid;\n    grid-template-columns: 1fr 1.6fr;\n    gap: 60px;\n    align-items: start;\n    width: 100%;\n}\n\n\/* \u2500\u2500 LEFT COLUMN \u2500\u2500 *\/\n.mrj-left h2 {\n    font-size: clamp(32px, 4vw, 48px);\n    font-weight: 700;\n    letter-spacing: -0.02em;\n    line-height: 1.1;\n    margin-bottom: 18px;\n    color: #ffffff;\n}\n.mrj-left p {\n    font-size: 14px;\n    font-weight: 300;\n    line-height: 1.7;\n    color: rgba(255,255,255,.6);\n}\n.mrj-left p span {\n    color: #c8102e;\n    font-weight: 500;\n    text-decoration: underline;\n    text-underline-offset: 3px;\n}\n\n\/* \u2500\u2500 FORM \u2500\u2500 *\/\n.mrj-form {\n    display: flex;\n    flex-direction: column;\n    gap: 0;\n}\n.mrj-field {\n    position: relative;\n    margin-bottom: 32px;\n}\n.mrj-field input,\n.mrj-field textarea,\n.mrj-field select {\n    width: 100%;\n    background: transparent;\n    border: none;\n    border-bottom: 1px solid rgba(255,255,255,.2);\n    color: #ffffff;\n    font-family: 'DM Sans', sans-serif;\n    font-size: 14px;\n    font-weight: 300;\n    padding: 10px 0;\n    outline: none;\n    transition: border-color .3s;\n    resize: none;\n    appearance: none;\n    -webkit-appearance: none;\n}\n.mrj-field select {\n    cursor: pointer;\n    background-image: none;\n}\n.mrj-field select option {\n    background: #1a1a1a;\n    color: #fff;\n}\n.mrj-select-wrap {\n    position: relative;\n}\n.mrj-select-wrap svg {\n    position: absolute;\n    right: 0;\n    top: 50%;\n    transform: translateY(-50%);\n    color: rgba(255,255,255,.4);\n    pointer-events: none;\n}\n.mrj-field input::placeholder,\n.mrj-field textarea::placeholder {\n    color: rgba(255,255,255,.35);\n    font-size: 14px;\n    font-weight: 300;\n}\n.mrj-field select:invalid,\n.mrj-field select.empty {\n    color: rgba(255,255,255,.35);\n}\n.mrj-field input:focus,\n.mrj-field textarea:focus,\n.mrj-field select:focus {\n    border-bottom-color: rgba(255,255,255,.7);\n}\n.mrj-field textarea {\n    min-height: 70px;\n}\n.mrj-field-line {\n    position: absolute;\n    bottom: 0; left: 0;\n    height: 1px;\n    width: 0%;\n    background: #c8102e;\n    transition: width .35s ease;\n}\n.mrj-field input:focus ~ .mrj-field-line,\n.mrj-field textarea:focus ~ .mrj-field-line,\n.mrj-field select:focus ~ .mrj-field-line {\n    width: 100%;\n}\n.mrj-row {\n    display: grid;\n    grid-template-columns: 1fr 1fr;\n    gap: 0 40px;\n}\n\n\/* CV upload *\/\n.mrj-upload-row {\n    display: flex;\n    align-items: center;\n    gap: 16px;\n    margin-bottom: 32px;\n}\n.mrj-upload-btn {\n    display: inline-flex;\n    align-items: center;\n    gap: 0;\n    cursor: pointer;\n    border: 1px solid rgba(255,255,255,.3);\n    background: none;\n    padding: 0;\n    font-family: inherit;\n    flex-shrink: 0;\n}\n.mrj-upload-btn-label {\n    color: #fff;\n    font-size: 13px;\n    font-weight: 500;\n    letter-spacing: 0.03em;\n    padding: 11px 18px;\n}\n.mrj-upload-btn-arrow {\n    background: #c8102e;\n    color: #fff;\n    width: 40px;\n    height: 40px;\n    display: flex;\n    align-items: center;\n    justify-content: center;\n    border-left: 1px solid rgba(255,255,255,.2);\n    flex-shrink: 0;\n}\n#mrjCvInput { display: none; }\n#mrjFileName {\n    font-size: 13px;\n    color: rgba(255,255,255,.5);\n    font-style: italic;\n}\n\n\/* bottom row *\/\n.mrj-bottom {\n    display: flex;\n    align-items: center;\n    justify-content: space-between;\n    margin-top: 8px;\n    flex-wrap: wrap;\n    gap: 16px;\n}\n.mrj-privacy {\n    display: flex;\n    align-items: center;\n    gap: 10px;\n    cursor: pointer;\n}\n.mrj-privacy input[type=\"checkbox\"] {\n    appearance: none;\n    -webkit-appearance: none;\n    width: 16px;\n    height: 16px;\n    border: 1px solid rgba(255,255,255,.3);\n    background: transparent;\n    cursor: pointer;\n    flex-shrink: 0;\n    transition: background .2s, border-color .2s;\n    position: relative;\n}\n.mrj-privacy input[type=\"checkbox\"]:checked {\n    background: #c8102e;\n    border-color: #c8102e;\n}\n.mrj-privacy input[type=\"checkbox\"]:checked::after {\n    content: '';\n    position: absolute;\n    top: 2px; left: 5px;\n    width: 4px; height: 8px;\n    border: 2px solid #fff;\n    border-top: none; border-left: none;\n    transform: rotate(45deg);\n}\n.mrj-privacy span {\n    font-size: 13px;\n    color: rgba(255,255,255,.5);\n}\n.mrj-privacy a {\n    color: rgba(255,255,255,.5);\n    text-decoration: underline;\n    text-underline-offset: 2px;\n}\n.mrj-privacy a:hover { color: #fff; }\n\n\/* submit *\/\n.mrj-submit {\n    display: flex;\n    align-items: center;\n    gap: 0;\n    cursor: pointer;\n    border: none;\n    background: none;\n    padding: 0;\n    font-family: inherit;\n}\n.mrj-submit-label {\n    background: #c8102e;\n    color: #fff;\n    font-family: 'DM Sans', sans-serif;\n    font-size: 14px;\n    font-weight: 500;\n    letter-spacing: 0.04em;\n    padding: 12px 22px;\n    transition: background .2s;\n}\n.mrj-submit:hover .mrj-submit-label { background: #a50d24; }\n.mrj-submit-arrow {\n    background: #c8102e;\n    color: #fff;\n    width: 44px;\n    height: 44px;\n    display: flex;\n    align-items: center;\n    justify-content: center;\n    border-left: 1px solid rgba(255,255,255,.2);\n    transition: background .2s;\n    flex-shrink: 0;\n}\n.mrj-submit:hover .mrj-submit-arrow { background: #a50d24; }\n\n\/* feedback *\/\n.mrj-feedback {\n    margin-top: 18px;\n    font-size: 14px;\n    font-weight: 500;\n    display: none;\n    padding: 12px 16px;\n    border-radius: 2px;\n}\n.mrj-feedback.success {\n    display: block;\n    background: rgba(40,180,80,.12);\n    color: #5ce08a;\n    border: 1px solid rgba(40,180,80,.3);\n}\n.mrj-feedback.error {\n    display: block;\n    background: rgba(200,16,46,.12);\n    color: #ff6b6b;\n    border: 1px solid rgba(200,16,46,.3);\n}\n\n@media (max-width: 768px) {\n    .mrj-wrap { grid-template-columns: 1fr; padding: 50px 24px; gap: 40px; }\n    .mrj-row  { grid-template-columns: 1fr; }\n    .mrj-upload-row { flex-wrap: wrap; }\n}\n<\/style>\n\n<div class=\"mrj-wrap\">\n\n    <!-- LEFT -->\n    <div class=\"mrj-left\">\n        <h2>Candidati<br>per collaborare<br>con noi<\/h2>\n        <p>Compila il form in tutte le sue parti <span>allegando il curriculum in pdf<\/span>. In caso di esito positivo sarai ricontattato dal nostro Team per un colloquio.<\/p>\n    <\/div>\n\n    <!-- RIGHT -->\n    <div>\n        <div class=\"mrj-form\">\n\n            <div class=\"mrj-field\">\n                <input type=\"text\" id=\"mrjNome\" placeholder=\"Nome e Cognome\" autocomplete=\"name\"\/>\n                <span class=\"mrj-field-line\"><\/span>\n            <\/div>\n\n            <div class=\"mrj-field\">\n                <div class=\"mrj-select-wrap\">\n                    <select id=\"mrjPosizione\" class=\"empty\">\n                        <option value=\"\" disabled selected>Posizione di interesse<\/option>\n                                                    <option value=\"Analista\">\n                                Analista                            <\/option>\n                                                    <option value=\"Collaboratori esterni\">\n                                Collaboratori esterni                            <\/option>\n                                                    <option value=\"Consulente legale\">\n                                Consulente legale                            <\/option>\n                                                    <option value=\"Operatore telemarketing\">\n                                Operatore telemarketing                            <\/option>\n                                            <\/select>\n                    <svg width=\"16\" height=\"16\" fill=\"none\" viewBox=\"0 0 24 24\" stroke=\"currentColor\" stroke-width=\"2\">\n                        <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n                    <\/svg>\n                <\/div>\n                <span class=\"mrj-field-line\"><\/span>\n            <\/div>\n\n            <div class=\"mrj-row\">\n                <div class=\"mrj-field\">\n                    <input type=\"email\" id=\"mrjEmail\" placeholder=\"Email\" autocomplete=\"email\"\/>\n                    <span class=\"mrj-field-line\"><\/span>\n                <\/div>\n                <div class=\"mrj-field\">\n                    <input type=\"tel\" id=\"mrjTelefono\" placeholder=\"Telefono\" autocomplete=\"tel\"\/>\n                    <span class=\"mrj-field-line\"><\/span>\n                <\/div>\n            <\/div>\n\n            <div class=\"mrj-field\">\n                <textarea id=\"mrjMessaggio\" placeholder=\"Breve presentazione...\" rows=\"3\"><\/textarea>\n                <span class=\"mrj-field-line\"><\/span>\n            <\/div>\n\n            <!-- CV Upload -->\n            <div class=\"mrj-upload-row\">\n                <input type=\"file\" id=\"mrjCvInput\" accept=\".pdf\"\/>\n                <label for=\"mrjCvInput\" class=\"mrj-upload-btn\">\n                    <span class=\"mrj-upload-btn-label\">Clicca per allegare il CV<\/span>\n                    <span class=\"mrj-upload-btn-arrow\">\n                        <svg width=\"16\" height=\"16\" fill=\"none\" viewBox=\"0 0 24 24\" stroke=\"currentColor\" stroke-width=\"2.2\">\n                            <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M5 10l7-7 7 7M12 3v14M5 21h14\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/label>\n                <span id=\"mrjFileName\">Nessun file selezionato<\/span>\n            <\/div>\n\n            <div class=\"mrj-bottom\">\n                <label class=\"mrj-privacy\">\n                    <input type=\"checkbox\" id=\"mrjPrivacy\"\/>\n                    <span>Accetto la <a href=\"\/privacy-policy\" target=\"_blank\">Privacy Policy<\/a><\/span>\n                <\/label>\n                <button class=\"mrj-submit\" id=\"mrjSubmit\" type=\"button\">\n                    <span class=\"mrj-submit-label\">Invia Candidatura<\/span>\n                    <span class=\"mrj-submit-arrow\">\n                        <svg width=\"16\" height=\"16\" fill=\"none\" viewBox=\"0 0 24 24\" stroke=\"currentColor\" stroke-width=\"2.2\">\n                            <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M5 12h14M13 6l6 6-6 6\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/button>\n            <\/div>\n\n            <div class=\"mrj-feedback\" id=\"mrjFeedback\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<script>\n(function() {\n    \/\/ Show filename on CV select\n    document.getElementById('mrjCvInput').addEventListener('change', function() {\n        var name = this.files.length ? this.files[0].name : 'Nessun file selezionato';\n        document.getElementById('mrjFileName').textContent = name;\n    });\n\n    \/\/ Remove empty class on select change\n    document.getElementById('mrjPosizione').addEventListener('change', function() {\n        this.classList.remove('empty');\n    });\n\n    document.getElementById('mrjSubmit').addEventListener('click', function() {\n        var nome      = document.getElementById('mrjNome').value.trim();\n        var posizione = document.getElementById('mrjPosizione').value.trim();\n        var email     = document.getElementById('mrjEmail').value.trim();\n        var telefono  = document.getElementById('mrjTelefono').value.trim();\n        var messaggio = document.getElementById('mrjMessaggio').value.trim();\n        var privacy   = document.getElementById('mrjPrivacy').checked;\n        var cvFile    = document.getElementById('mrjCvInput').files[0];\n        var feedback  = document.getElementById('mrjFeedback');\n\n        if (!nome || !email || !posizione) {\n            feedback.className = 'mrj-feedback error';\n            feedback.textContent = 'Per favore compila almeno Nome, Posizione ed Email.';\n            return;\n        }\n        if (!\/^[^\\s@]+@[^\\s@]+\\.[^\\s@]+$\/.test(email)) {\n            feedback.className = 'mrj-feedback error';\n            feedback.textContent = 'Inserisci un indirizzo email valido.';\n            return;\n        }\n        if (!privacy) {\n            feedback.className = 'mrj-feedback error';\n            feedback.textContent = 'Devi accettare la Privacy Policy per inviare il modulo.';\n            return;\n        }\n\n        var btn = document.getElementById('mrjSubmit');\n        btn.style.opacity = '0.5';\n        btn.style.pointerEvents = 'none';\n        feedback.className = 'mrj-feedback';\n        feedback.textContent = '';\n\n        var data = new FormData();\n        data.append('action',    'mrj_send_application');\n        data.append('nonce',     mrj_ajax.nonce);\n        data.append('nome',      nome);\n        data.append('posizione', posizione);\n        data.append('email',     email);\n        data.append('telefono',  telefono);\n        data.append('messaggio', messaggio);\n        if (cvFile) data.append('cv', cvFile);\n\n        fetch(mrj_ajax.url, { method: 'POST', body: data })\n            .then(function(r) { return r.json(); })\n            .then(function(res) {\n                if (res.success) {\n                    feedback.className = 'mrj-feedback success';\n                    feedback.textContent = 'Candidatura inviata! Ti contatteremo al pi\u00f9 presto.';\n                    document.getElementById('mrjNome').value = '';\n                    document.getElementById('mrjPosizione').value = '';\n                    document.getElementById('mrjPosizione').classList.add('empty');\n                    document.getElementById('mrjEmail').value = '';\n                    document.getElementById('mrjTelefono').value = '';\n                    document.getElementById('mrjMessaggio').value = '';\n                    document.getElementById('mrjCvInput').value = '';\n                    document.getElementById('mrjFileName').textContent = 'Nessun file selezionato';\n                    document.getElementById('mrjPrivacy').checked = false;\n                } else {\n                    feedback.className = 'mrj-feedback error';\n                    feedback.textContent = 'Si \u00e8 verificato un errore. Riprova o contattaci direttamente.';\n                }\n                btn.style.opacity = '';\n                btn.style.pointerEvents = '';\n            })\n            .catch(function() {\n                feedback.className = 'mrj-feedback error';\n                feedback.textContent = 'Errore di rete. Riprova o contattaci direttamente.';\n                btn.style.opacity = '';\n                btn.style.pointerEvents = '';\n            });\n    });\n})();\n<\/script>\n\n<\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:75px;--awb-padding-bottom:75px;--awb-padding-top-small:0px;--awb-padding-bottom-small:0px;--awb-background-color:var(--awb-color2);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n    <!-- Google Fonts \u2013 Inter -->\n    \n    <style>\n        \/* \u2500\u2500 Container \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-wrap {\n            max-width: 1200px !important;\n            margin: 0 auto !important;\n            padding: 60px 20px !important;\n            font-family: 'Inter', sans-serif !important;\n        }\n\n        \/* \u2500\u2500 Section Title \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-title,\n        .mj-6a046cabdd9f2-wrap h2.mj-6a046cabdd9f2-title {\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 700 !important;\n            font-size: 40px !important;\n            line-height: 1.15 !important;\n            color: #1a1a1a !important;\n            margin: 0 0 48px 0 !important;\n            padding: 0 !important;\n            letter-spacing: 0 !important;\n            text-transform: none !important;\n        }\n\n        \/* \u2500\u2500 Accordion Item \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-item {\n            border-top: 1px solid #e0e0e0 !important;\n        }\n        .mj-6a046cabdd9f2-item:last-child {\n            border-bottom: 1px solid #e0e0e0 !important;\n        }\n\n        \/* \u2500\u2500 Accordion Header (clickable row) \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-header {\n            display: flex !important;\n            align-items: center !important;\n            justify-content: space-between !important;\n            padding: 24px 0 !important;\n            cursor: pointer !important;\n            gap: 20px !important;\n            -webkit-user-select: none;\n            user-select: none;\n        }\n\n        .mj-6a046cabdd9f2-header:hover .mj-6a046cabdd9f2-job-title {\n            color: #c8102e !important;\n        }\n\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-job-title,\n        .mj-6a046cabdd9f2-wrap h3.mj-6a046cabdd9f2-job-title {\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 700 !important;\n            font-size: 24px !important;\n            line-height: 1.3 !important;\n            color: #1a1a1a !important;\n            margin: 0 !important;\n            padding: 0 !important;\n            letter-spacing: 0 !important;\n            text-transform: none !important;\n            transition: color .2s ease;\n        }\n\n        \/* \u2500\u2500 Arrow Icon Button \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-arrow {\n            flex-shrink: 0;\n            width: 40px !important;\n            height: 40px !important;\n            display: flex !important;\n            align-items: center !important;\n            justify-content: center !important;\n            border: none !important;\n            background: none !important;\n            cursor: pointer !important;\n            padding: 0 !important;\n            transition: transform .3s ease;\n        }\n        .mj-6a046cabdd9f2-arrow svg {\n            width: 28px !important;\n            height: 28px !important;\n            display: block !important;\n        }\n\n        \/* Rotate arrow when open *\/\n        .mj-6a046cabdd9f2-item.is-open .mj-6a046cabdd9f2-arrow {\n            transform: rotate(90deg) !important;\n        }\n\n        \/* \u2500\u2500 Accordion Body (expandable content) \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-body {\n            max-height: 0;\n            overflow: hidden !important;\n            transition: max-height .4s ease, opacity .3s ease;\n            opacity: 0;\n        }\n        .mj-6a046cabdd9f2-item.is-open .mj-6a046cabdd9f2-body {\n            opacity: 1;\n        }\n\n        .mj-6a046cabdd9f2-content {\n            padding: 0 0 40px 0 !important;\n        }\n\n        \/* \u2500\u2500 Description text \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc,\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc p,\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc li,\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc span {\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 400 !important;\n            font-size: 18px !important;\n            line-height: 1.7 !important;\n            color: #333 !important;\n        }\n        .mj-6a046cabdd9f2-desc {\n            margin: 0 0 32px 0 !important;\n        }\n        .mj-6a046cabdd9f2-desc p {\n            margin: 0 0 14px 0 !important;\n        }\n        .mj-6a046cabdd9f2-desc p:last-child {\n            margin-bottom: 0 !important;\n        }\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc strong,\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-desc b {\n            font-weight: 700 !important;\n            color: #1a1a1a !important;\n            font-size: 18px !important;\n        }\n        .mj-6a046cabdd9f2-desc ul,\n        .mj-6a046cabdd9f2-desc ol {\n            margin: 8px 0 14px 0 !important;\n            padding-left: 20px !important;\n        }\n        .mj-6a046cabdd9f2-desc li {\n            margin-bottom: 4px !important;\n        }\n        .mj-6a046cabdd9f2-desc em,\n        .mj-6a046cabdd9f2-desc i {\n            font-style: italic !important;\n        }\n\n        \/* \u2500\u2500 CTA Button \u2500\u2500 *\/\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-cta,\n        .mj-6a046cabdd9f2-wrap a.mj-6a046cabdd9f2-cta {\n            display: inline-flex !important;\n            align-items: center !important;\n            gap: 12px !important;\n            font-family: 'Inter', sans-serif !important;\n            font-weight: 600 !important;\n            font-size: 16px !important;\n            color: #1a1a1a !important;\n            text-decoration: none !important;\n            border: 1.5px solid #1a1a1a !important;\n            border-radius: 0 !important;\n            padding: 12px 20px !important;\n            background: transparent !important;\n            cursor: pointer !important;\n            transition: all .25s ease;\n            line-height: 1 !important;\n        }\n        .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-cta:hover,\n        .mj-6a046cabdd9f2-wrap a.mj-6a046cabdd9f2-cta:hover {\n            background: #c8102e !important;\n            border-color: #c8102e !important;\n            color: #fff !important;\n        }\n        .mj-6a046cabdd9f2-cta:hover .mj-6a046cabdd9f2-cta-arrow svg {\n            fill: #fff !important;\n        }\n        .mj-6a046cabdd9f2-cta-arrow {\n            display: flex !important;\n            align-items: center !important;\n            justify-content: center !important;\n            width: 28px !important;\n            height: 28px !important;\n            background: #c8102e !important;\n            border-radius: 50% !important;\n            flex-shrink: 0;\n            transition: background .25s ease;\n        }\n        .mj-6a046cabdd9f2-cta:hover .mj-6a046cabdd9f2-cta-arrow {\n            background: #fff !important;\n        }\n        .mj-6a046cabdd9f2-cta:hover .mj-6a046cabdd9f2-cta-arrow svg {\n            fill: #c8102e !important;\n        }\n        .mj-6a046cabdd9f2-cta-arrow svg {\n            width: 14px !important;\n            height: 14px !important;\n            fill: #fff !important;\n            transition: fill .25s ease;\n        }\n\n        \/* \u2500\u2500 Responsive \u2500\u2500 *\/\n        @media (max-width: 768px) {\n            .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-title,\n            .mj-6a046cabdd9f2-wrap h2.mj-6a046cabdd9f2-title {\n                font-size: 28px !important;\n                margin-bottom: 32px !important;\n            }\n            .mj-6a046cabdd9f2-wrap .mj-6a046cabdd9f2-job-title,\n            .mj-6a046cabdd9f2-wrap h3.mj-6a046cabdd9f2-job-title {\n                font-size: 19px !important;\n            }\n            .mj-6a046cabdd9f2-header {\n                padding: 20px 0 !important;\n            }\n            .mj-6a046cabdd9f2-wrap {\n                padding: 40px 16px !important;\n            }\n        }\n    <\/style>\n\n    <div class=\"mj-6a046cabdd9f2-wrap\">\n\n        <h2 class=\"mj-6a046cabdd9f2-title\">Posizioni aperte<\/h2>\n\n        \n            <div class=\"mj-6a046cabdd9f2-item\">\n\n                <!-- Header Row -->\n                <div class=\"mj-6a046cabdd9f2-header\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\">\n                    <h3 class=\"mj-6a046cabdd9f2-job-title\">Consulente legale<\/h3>\n                    <span class=\"mj-6a046cabdd9f2-arrow\">\n                        <svg viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <rect width=\"24\" height=\"24\" rx=\"0\" fill=\"#c8102e\"\/>\n                            <path d=\"M9 6l6 6-6 6\" stroke=\"#fff\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n\n                <!-- Expandable Body -->\n                <div class=\"mj-6a046cabdd9f2-body\">\n                    <div class=\"mj-6a046cabdd9f2-content\">\n                        <div class=\"mj-6a046cabdd9f2-desc\">\n                            <p>Martingale Risk ricerca per la propria sede di Roma una risorsa legale laureata in Giurisprudenza e\/o un giovane avvocato da inserire nel Team di Analisti Quantitativi e di Legali specializzati nel diritto bancario e finanziario.<\/p>\n<p>La risorsa sar\u00e0 inserita in un contesto dinamico, innovativo ed avr\u00e0 la possibilit\u00e0 di intraprendere un percorso di crescita professionale di estremo rilievo grazie all\u2019elevata importanza del contenzioso finanziario in gestione, estremamente di valore in termini di importi e complessit\u00e0. Inoltre, previo periodo di previo periodo di formazione professionale tecnica, si interfaccer\u00e0 costantemente con i ns analisti specializzati in ingegneria finanziaria per la predisposizione e\/o revisione di atti giuridici in un\u2019ottica di costante aggiornamento dell\u2019evoluzione giurisprudenziale di settore e l\u2019approfondito studio della normativa finanziaria e bancaria di cui al Testo Unico Finanziario e Bancario (TUF e TUB).<\/p>\n<p>Consideriamo requisiti fondamentali:<\/p>\n<ul role=\"list\">\n<li>Laurea in Giurisprudenza;<\/li>\n<li>Utilizzo strumenti informatici;<\/li>\n<li>Ottime capacit\u00e0 di lavorare sia in team che in maniera autonoma;<\/li>\n<li>Spirito propositivo e indipendente;<\/li>\n<li>Capacit\u00e0 comunicativa;<\/li>\n<li>Flessibilit\u00e0;<\/li>\n<li>Organizzazione e gestione del tempo.<\/li>\n<\/ul>\n<p>Offerta Contrattuale<br \/>\nSi offre assunzione a tempo indeterminato con retribuzione commisurata all\u2019esperienza della risorsa.<br \/>\nOrario di lavoro:\u00a0full time (9:00 \u2013 18:00)<br \/>\nLuogo di lavoro:\u00a0Largo del Nazareno, 15 \u2013 Roma Centro<\/p>\n                        <\/div>\n\n                        <a href=\"#candidati-form\" class=\"mj-6a046cabdd9f2-cta\">\n                            Candidati per questa posizione\n                            <span class=\"mj-6a046cabdd9f2-cta-arrow\">\n                                <svg viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                    <path d=\"M5 12h14M13 6l6 6-6 6\"\/>\n                                <\/svg>\n                            <\/span>\n                        <\/a>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"mj-6a046cabdd9f2-item\">\n\n                <!-- Header Row -->\n                <div class=\"mj-6a046cabdd9f2-header\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\">\n                    <h3 class=\"mj-6a046cabdd9f2-job-title\">Analista<\/h3>\n                    <span class=\"mj-6a046cabdd9f2-arrow\">\n                        <svg viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <rect width=\"24\" height=\"24\" rx=\"0\" fill=\"#c8102e\"\/>\n                            <path d=\"M9 6l6 6-6 6\" stroke=\"#fff\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n\n                <!-- Expandable Body -->\n                <div class=\"mj-6a046cabdd9f2-body\">\n                    <div class=\"mj-6a046cabdd9f2-content\">\n                        <div class=\"mj-6a046cabdd9f2-desc\">\n                            <p>Martingale Risk ricerca per la propria sede di Roma una risorsa legale laureata in Giurisprudenza e\/o un giovane avvocato da inserire nel Team di Analisti Quantitativi e di Legali specializzati nel diritto bancario e finanziario.<\/p>\n<p>La risorsa sar\u00e0 inserita in un contesto dinamico, innovativo ed avr\u00e0 la possibilit\u00e0 di intraprendere un percorso di crescita professionale di estremo rilievo grazie all\u2019elevata importanza del contenzioso finanziario in gestione, estremamente di valore in termini di importi e complessit\u00e0. Inoltre, previo periodo di previo periodo di formazione professionale tecnica, si interfaccer\u00e0 costantemente con i ns analisti specializzati in ingegneria finanziaria per la predisposizione e\/o revisione di atti giuridici in un\u2019ottica di costante aggiornamento dell\u2019evoluzione giurisprudenziale di settore e l\u2019approfondito studio della normativa finanziaria e bancaria di cui al Testo Unico Finanziario e Bancario (TUF e TUB).<\/p>\n<p>Consideriamo requisiti fondamentali:<\/p>\n<ul role=\"list\">\n<li>Laurea in Giurisprudenza;<\/li>\n<li>Utilizzo strumenti informatici;<\/li>\n<li>Ottime capacit\u00e0 di lavorare sia in team che in maniera autonoma;<\/li>\n<li>Spirito propositivo e indipendente;<\/li>\n<li>Capacit\u00e0 comunicativa;<\/li>\n<li>Flessibilit\u00e0;<\/li>\n<li>Organizzazione e gestione del tempo.<\/li>\n<\/ul>\n<p>Offerta Contrattuale<br \/>\nSi offre assunzione a tempo indeterminato con retribuzione commisurata all\u2019esperienza della risorsa.<br \/>\nOrario di lavoro:\u00a0full time (9:00 \u2013 18:00)<br \/>\nLuogo di lavoro:\u00a0Largo del Nazareno, 15 \u2013 Roma Centro<\/p>\n                        <\/div>\n\n                        <a href=\"#candidati-form\" class=\"mj-6a046cabdd9f2-cta\">\n                            Candidati per questa posizione\n                            <span class=\"mj-6a046cabdd9f2-cta-arrow\">\n                                <svg viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                    <path d=\"M5 12h14M13 6l6 6-6 6\"\/>\n                                <\/svg>\n                            <\/span>\n                        <\/a>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"mj-6a046cabdd9f2-item\">\n\n                <!-- Header Row -->\n                <div class=\"mj-6a046cabdd9f2-header\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\">\n                    <h3 class=\"mj-6a046cabdd9f2-job-title\">Operatore telemarketing<\/h3>\n                    <span class=\"mj-6a046cabdd9f2-arrow\">\n                        <svg viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <rect width=\"24\" height=\"24\" rx=\"0\" fill=\"#c8102e\"\/>\n                            <path d=\"M9 6l6 6-6 6\" stroke=\"#fff\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n\n                <!-- Expandable Body -->\n                <div class=\"mj-6a046cabdd9f2-body\">\n                    <div class=\"mj-6a046cabdd9f2-content\">\n                        <div class=\"mj-6a046cabdd9f2-desc\">\n                            <p>Martingale Risk ricerca per la propria sede di Roma una risorsa legale laureata in Giurisprudenza e\/o un giovane avvocato da inserire nel Team di Analisti Quantitativi e di Legali specializzati nel diritto bancario e finanziario.<\/p>\n<p>La risorsa sar\u00e0 inserita in un contesto dinamico, innovativo ed avr\u00e0 la possibilit\u00e0 di intraprendere un percorso di crescita professionale di estremo rilievo grazie all\u2019elevata importanza del contenzioso finanziario in gestione, estremamente di valore in termini di importi e complessit\u00e0. Inoltre, previo periodo di previo periodo di formazione professionale tecnica, si interfaccer\u00e0 costantemente con i ns analisti specializzati in ingegneria finanziaria per la predisposizione e\/o revisione di atti giuridici in un\u2019ottica di costante aggiornamento dell\u2019evoluzione giurisprudenziale di settore e l\u2019approfondito studio della normativa finanziaria e bancaria di cui al Testo Unico Finanziario e Bancario (TUF e TUB).<\/p>\n<p>Consideriamo requisiti fondamentali:<\/p>\n<ul role=\"list\">\n<li>Laurea in Giurisprudenza;<\/li>\n<li>Utilizzo strumenti informatici;<\/li>\n<li>Ottime capacit\u00e0 di lavorare sia in team che in maniera autonoma;<\/li>\n<li>Spirito propositivo e indipendente;<\/li>\n<li>Capacit\u00e0 comunicativa;<\/li>\n<li>Flessibilit\u00e0;<\/li>\n<li>Organizzazione e gestione del tempo.<\/li>\n<\/ul>\n<p>Offerta Contrattuale<br \/>\nSi offre assunzione a tempo indeterminato con retribuzione commisurata all\u2019esperienza della risorsa.<\/p>\n                        <\/div>\n\n                        <a href=\"#candidati-form\" class=\"mj-6a046cabdd9f2-cta\">\n                            Candidati per questa posizione\n                            <span class=\"mj-6a046cabdd9f2-cta-arrow\">\n                                <svg viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                    <path d=\"M5 12h14M13 6l6 6-6 6\"\/>\n                                <\/svg>\n                            <\/span>\n                        <\/a>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n            <div class=\"mj-6a046cabdd9f2-item\">\n\n                <!-- Header Row -->\n                <div class=\"mj-6a046cabdd9f2-header\" role=\"button\" tabindex=\"0\" aria-expanded=\"false\">\n                    <h3 class=\"mj-6a046cabdd9f2-job-title\">Collaboratori esterni<\/h3>\n                    <span class=\"mj-6a046cabdd9f2-arrow\">\n                        <svg viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <rect width=\"24\" height=\"24\" rx=\"0\" fill=\"#c8102e\"\/>\n                            <path d=\"M9 6l6 6-6 6\" stroke=\"#fff\" stroke-width=\"2.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n\n                <!-- Expandable Body -->\n                <div class=\"mj-6a046cabdd9f2-body\">\n                    <div class=\"mj-6a046cabdd9f2-content\">\n                        <div class=\"mj-6a046cabdd9f2-desc\">\n                            <p>Martingale Risk ricerca per la propria sede di Roma una risorsa legale laureata in Giurisprudenza e\/o un giovane avvocato da inserire nel Team di Analisti Quantitativi e di Legali specializzati nel diritto bancario e finanziario.<\/p>\n<p>La risorsa sar\u00e0 inserita in un contesto dinamico, innovativo ed avr\u00e0 la possibilit\u00e0 di intraprendere un percorso di crescita professionale di estremo rilievo grazie all\u2019elevata importanza del contenzioso finanziario in gestione, estremamente di valore in termini di importi e complessit\u00e0. Inoltre, previo periodo di previo periodo di formazione professionale tecnica, si interfaccer\u00e0 costantemente con i ns analisti specializzati in ingegneria finanziaria per la predisposizione e\/o revisione di atti giuridici in un\u2019ottica di costante aggiornamento dell\u2019evoluzione giurisprudenziale di settore e l\u2019approfondito studio della normativa finanziaria e bancaria di cui al Testo Unico Finanziario e Bancario (TUF e TUB).<\/p>\n<p>Consideriamo requisiti fondamentali:<\/p>\n<ul role=\"list\">\n<li>Laurea in Giurisprudenza;<\/li>\n<li>Utilizzo strumenti informatici;<\/li>\n<li>Ottime capacit\u00e0 di lavorare sia in team che in maniera autonoma;<\/li>\n<li>Spirito propositivo e indipendente;<\/li>\n<li>Capacit\u00e0 comunicativa;<\/li>\n<li>Flessibilit\u00e0;<\/li>\n<li>Organizzazione e gestione del tempo.<\/li>\n<\/ul>\n<p>Offerta Contrattuale<br \/>\nSi offre assunzione a tempo indeterminato con retribuzione commisurata all\u2019esperienza della risorsa.<\/p>\n                        <\/div>\n\n                        <a href=\"#candidati-form\" class=\"mj-6a046cabdd9f2-cta\">\n                            Candidati per questa posizione\n                            <span class=\"mj-6a046cabdd9f2-cta-arrow\">\n                                <svg viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                    <path d=\"M5 12h14M13 6l6 6-6 6\"\/>\n                                <\/svg>\n                            <\/span>\n                        <\/a>\n                    <\/div>\n                <\/div>\n\n            <\/div>\n\n        \n    <\/div>\n\n    <script>\n    (function(){\n        var uid = 'mj-6a046cabdd9f2';\n        var items = document.querySelectorAll('.' + uid + '-item');\n\n        items.forEach(function(item){\n            var header = item.querySelector('.' + uid + '-header');\n            var body   = item.querySelector('.' + uid + '-body');\n\n            function toggle(){\n                var isOpen = item.classList.contains('is-open');\n\n                \/\/ Close all others (accordion behaviour \u2014 only one open at a time)\n                items.forEach(function(other){\n                    if (other !== item && other.classList.contains('is-open')) {\n                        other.classList.remove('is-open');\n                        var otherBody = other.querySelector('.' + uid + '-body');\n                        otherBody.style.maxHeight = null;\n                        other.querySelector('.' + uid + '-header').setAttribute('aria-expanded', 'false');\n                    }\n                });\n\n                if (isOpen) {\n                    item.classList.remove('is-open');\n                    body.style.maxHeight = null;\n                    header.setAttribute('aria-expanded', 'false');\n                } else {\n                    item.classList.add('is-open');\n                    body.style.maxHeight = body.scrollHeight + 'px';\n                    header.setAttribute('aria-expanded', 'true');\n\n                    \/\/ Smooth scroll to header if it's above viewport\n                    setTimeout(function(){\n                        var rect = header.getBoundingClientRect();\n                        if (rect.top < 0) {\n                            header.scrollIntoView({ behavior: 'smooth', block: 'start' });\n                        }\n                    }, 100);\n                }\n            }\n\n            header.addEventListener('click', toggle);\n            header.addEventListener('keydown', function(e){\n                if (e.key === 'Enter' || e.key === ' ') {\n                    e.preventDefault();\n                    toggle();\n                }\n            });\n        });\n\n        \/\/ CTA: smooth scroll to the candidati-form container\n        var wrap = document.querySelector('.' + uid + '-wrap');\n        var ctaButtons = wrap.querySelectorAll('a[href=\"#candidati-form\"]');\n        ctaButtons.forEach(function(btn){\n            btn.addEventListener('click', function(e){\n                e.preventDefault();\n                var target = document.getElementById('candidati-form');\n                if (target) {\n                    target.scrollIntoView({ behavior: 'smooth', block: 'start' });\n                }\n            });\n        });\n    })();\n    <\/script>\n\n    <\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavora con noi - Martingale Risk<\/title>\n<meta name=\"description\" content=\"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavora con noi - Martingale Risk\" \/>\n<meta property=\"og:description\" content=\"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T07:39:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/lavora-con-noi\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/lavora-con-noi\\\/\",\"name\":\"Lavora con noi - Martingale Risk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"datePublished\":\"2026-03-19T09:52:34+00:00\",\"dateModified\":\"2026-05-06T07:39:00+00:00\",\"description\":\"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/lavora-con-noi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/lavora-con-noi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/lavora-con-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavora con noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavora con noi - Martingale Risk","description":"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Lavora con noi - Martingale Risk","og_description":"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!","og_url":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/","og_site_name":"Martingale","article_modified_time":"2026-05-06T07:39:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/","url":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/","name":"Lavora con noi - Martingale Risk","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"datePublished":"2026-03-19T09:52:34+00:00","dateModified":"2026-05-06T07:39:00+00:00","description":"Scopri tutte le opportunit\u00e0 lavorative della Martingale Risk. Lavora con noi o collabora come professionista esterno!","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/lavora-con-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"Lavora con noi"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":25,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":39472,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/pages\/25\/revisions\/39472"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}