{"id":12704,"date":"2017-06-01T17:41:26","date_gmt":"2017-06-01T15:41:26","guid":{"rendered":"http:\/\/mgr.macoweb.eu\/?p=12704"},"modified":"2017-06-01T17:41:26","modified_gmt":"2017-06-01T15:41:26","slug":"corte-di-appello-di-torino-contratti-derivati","status":"publish","type":"post","link":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/","title":{"rendered":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2>Annullamento dei contratti derivati<\/h2>\n<p>Societ\u00e0 piemontese fa valere i propri diritti in giudizio e recupera mezzo milione di Euro persi a causa dei derivati sbagliati, i contratti derivati sono stati annullati.<\/p>\n<p>Decisiva la Sentenza n. 858\/17 dep. il 19\/04\/17 della Corte D\u2019Appello di Torino, che ha condannato la nota banca nazionale a rimborsare Euro 523.000 a titolo di risarcimento, ribadendo cos\u00ec il principio della nullit\u00e0 di quei contratti derivati che vengono proposti dalle banche, e sottoscritti dai clienti, con la dichiarata finalit\u00e0 di copertura contro il rischio di aumento dei tassi di interesse di un indebitamento sottostante ma che, in realt\u00e0, non sono idonei a soddisfare tale scopo proprio per la struttura finanziaria che li caratterizza.<\/p>\n<p>Dal 2000 al 2006 la societ\u00e0, che gestisce attivit\u00e0 alberghiere sul lago Maggiore, ha stipulato con la banca cinque contratti derivati SWAP, tutti con la dichiarata finalit\u00e0 di copertura dal rischio di aumento dei tassi di interesse su un mutuo acceso a tasso variabile.<\/p>\n<p>Successivamente, la societ\u00e0 ha agito in giudizio chiedendo la dichiarazione di nullit\u00e0 dei contratti stipulati e la conseguente restituzione dei differenziali negativi pagati. Il CTU nominato dal Giudice ha effettivamente ravvisato la presenza di commissioni implicite a carico della societ\u00e0 non dichiarate dalla banca al momento della sottoscrizione del contratto, tali da rendere sproporzionato il rischio (alea) esistente tra le parti. Inoltre ha accertato che la natura meramente speculativa anzich\u00e9 di copertura dei contratti sottoscritti tra le parti.<\/p>\n<p>In tal modo la banca sarebbe venuta meno al dovere di informazione sui rischi attinenti l\u2019operazione finanziaria ex art. 21 del TUF, che vanno necessariamente dichiarati in quanto da essi pu\u00f2 dipendere l\u2019interesse del cliente ed il rischio a cui esso decide di esporsi.<\/p>\n<p>Tale mancata indicazione ha comportato un grave inadempimento da parte dell\u2019istituto di credito, che ha portato alla <span style=\"text-decoration: underline;\">risoluzione dei derivati<\/span> oggetto di vertenza e la <span style=\"text-decoration: underline;\">restituzione di tutte le perdite<\/span> provocate all\u2019azienda cliente.<\/p>\n<p>Recentemente, anche l\u2019appello presentato in giudizio dalla banca \u00e8 stato dichiarato inammissibile. La Corte d\u2019Appello ha infatti condiviso l\u2019orientamento del Giudice di primo grado e confermato il risarcimento in favore dell\u2019impresa di Euro 523.000.<\/p>\n<h2>Perch\u00e9 Martingale Risk pu\u00f2 intervenire<\/h2>\n<p><strong><span style=\"text-decoration: underline;\">Martingale Risk, in tema di contratti derivati, ha maturato un curriculum rilevante di <\/span><\/strong><a href=\"http:\/\/mgr.macoweb.eu\/casi-di-successo\/\"><strong><em>Casi di successo<\/em><\/strong><\/a><strong><span style=\"text-decoration: underline;\">, avendo chiuso in fase stragiudiziale o in corso di causa numerose transazioni e permesso a tanti clienti \u00a0di risolvere il \u201cproblema derivati\u201d, recuperando le perdite subite e le somme indebitamente corrisposte alla banca.<\/span><\/strong><\/p>\n<p><strong>Fonte:\u00a0<a href=\"http:\/\/mgr.macoweb.eu\/wp-content\/uploads\/2012\/07\/Articolo-corte-appello-torino.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Articolo<\/a><\/strong><\/p>\n<p>Per prenotare un <strong><em>check-up gratuito<\/em><\/strong> \u00e8 sufficiente compilare il form sul <a href=\"http:\/\/mgr.macoweb.eu\/contatti\/\">nostro sito<\/a>\u00a0oppure scrivere a <a href=\"mailto:info@martingalerisk.com\">info@martingalerisk.com<\/a> o contattare i ns uffici ai seguenti recapiti telefonici:<\/p>\n<p><strong>Roma \u2013 Largo del Nazareno, 15<\/strong><\/p>\n<p>Tel. 800 057750 \u2013 06\/32652828<\/p>\n<p><strong>Milano \u2013 Via Privata Maria Teresa, 4<\/strong><\/p>\n<p>Tel. 02\/89092280<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,18],"tags":[],"class_list":["post-12704","post","type-post","status-publish","format-standard","hentry","category-approfondimenti-derivati","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale<\/title>\n<meta name=\"description\" content=\"Scopri come la Corte d&#039;appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale\" \/>\n<meta property=\"og:description\" content=\"Scopri come la Corte d&#039;appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-01T15:41:26+00:00\" \/>\n<meta name=\"author\" content=\"Nicol\u00f2 Uccellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00f2 Uccellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/\"},\"author\":{\"name\":\"Nicol\u00f2 Uccellini\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"headline\":\"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI\",\"datePublished\":\"2017-06-01T15:41:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/\"},\"wordCount\":690,\"commentCount\":0,\"articleSection\":[\"Approfondimenti Derivati\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/\",\"name\":\"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"datePublished\":\"2017-06-01T15:41:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"description\":\"Scopri come la Corte d'appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/corte-di-appello-di-torino-contratti-derivati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\",\"name\":\"Nicol\u00f2 Uccellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00f2 Uccellini\"},\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale","description":"Scopri come la Corte d'appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale","og_description":"Scopri come la Corte d'appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese","og_url":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/","og_site_name":"Martingale","article_published_time":"2017-06-01T15:41:26+00:00","author":"Nicol\u00f2 Uccellini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicol\u00f2 Uccellini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/#article","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/"},"author":{"name":"Nicol\u00f2 Uccellini","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"headline":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI","datePublished":"2017-06-01T15:41:26+00:00","mainEntityOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/"},"wordCount":690,"commentCount":0,"articleSection":["Approfondimenti Derivati","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/","url":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/","name":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"datePublished":"2017-06-01T15:41:26+00:00","author":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"description":"Scopri come la Corte d'appello di Torino in una Sentenza del 2017 ha annullato i contratti derivati per conto di una Societ\u00e0 piemontese","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/corte-di-appello-di-torino-contratti-derivati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"CORTE D\u2019APPELLO DI TORINO: NULLI I CONTRATTI DERIVATI CHE NON PROTEGGONO DA AUMENTO TASSI"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5","name":"Nicol\u00f2 Uccellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","caption":"Nicol\u00f2 Uccellini"},"url":"https:\/\/sviluppodunp.it\/martingale\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/12704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=12704"}],"version-history":[{"count":0,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/12704\/revisions"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=12704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categories?post=12704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/tags?post=12704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}