{"id":25309,"date":"2021-11-11T13:07:08","date_gmt":"2021-11-11T12:07:08","guid":{"rendered":"http:\/\/mgr.macoweb.eu\/?p=25309"},"modified":"2021-11-11T13:07:08","modified_gmt":"2021-11-11T12:07:08","slug":"aziende-nuova-cassazione-derivati","status":"publish","type":"post","link":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/","title":{"rendered":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Dal 2009 ad oggi, <strong>Martingale Risk<\/strong> assiste la propria clientela nel recupero delle perdite illegittimamente subite nei rapporti bancari e finanziari, <strong><u>senza alcun tipo di compenso anticipato<\/u><\/strong> e offrendo il vantaggio competitivo di <strong><u>farsi carico di tutti i compensi legali, del costo delle perizie e delle spese amministrative relative alla causa.<\/u><\/strong><\/p>\n<p>Con la recentissima Sentenza della Cassazione n.21830\/2021, la societ\u00e0 leader in Italia permetter\u00e0 alle aziende di citare in causa le banche per ottenere la nullit\u00e0 dei contratti derivati.<\/p>\n<p><strong>LA VICENDA<\/strong><\/p>\n<p><strong>Una primaria banca nazionale impugna la Sentenza della Corte d&#8217;Appello di Milano<\/strong>, che nel 2018 si era espressa a favore di un\u2019azienda operante nel settore agricolo, dichiarando la <strong>nullit\u00e0 del contratto <em>interest rate swap<\/em> (IRS)<\/strong> stipulato nel 2011 con il proprio istituto di credito.<\/p>\n<p>I motivi di nullit\u00e0 si basavano sulla presenza di una <strong>contabilizzazione illegittima<\/strong> dell\u2019indice <strong><em>mark-to-market <\/em><\/strong>&#8211; inizialmente negativo e non comunicato al cliente &#8211; tanto nel suo valore, quanto nei <strong>criteri di calcolo<\/strong> impiegati per <strong>determinarlo<\/strong>. Il <strong>derivato IRS<\/strong> prevedeva che l&#8217;azienda versasse alla banca, con cadenza semestrale, un tasso fisso del 2% e ricevesse in cambio un tasso variabile (Euribor a 3 mesi). Lo strumento finanziario era stato dunque stipulato come garanzia di copertura dal rischio di un futuro rialzo dei tassi di interesse, mentre con il tempo si \u00e8 rivelato particolarmente sfavorevole nei confronti del cliente. Successivamente, la banca ha tentato di difendersi sostenendo che l\u2019indice <strong><em>mark-to-market<\/em><\/strong> sia un valore puramente teorico e virtuale, e che come tale non inciderebbe realmente sulle prestazioni a carico di ciascuna parte. In tal senso, la condivisione delle informazioni inerenti alle formule di calcolo ed ai parametri economici riportate nel contratto sarebbero state sufficienti a renderlo determinato o determinabile.<\/p>\n<p><strong>LA DECISIONE DELLA CORTE DI CASSAZIONE<\/strong><\/p>\n<p>La decisione finale della <strong>Corte<\/strong> si basa sull\u2019assunto che i <strong>derivati, espressione di una logica probabilistica,<\/strong> sono per loro natura <strong>contratti atipici<\/strong> a cui si applicano le leggi del mercato finanziario. In questo caso &#8211; pur restando vero che l\u2019<strong>IRS<\/strong> assolve la propria finalit\u00e0 di copertura &#8211; esso conserva la caratterizzazione di strumento di <strong>gestione del rischio finanziario<\/strong> che qualifica un contratto valido qualora persegua interessi meritevoli di <strong>tutela <\/strong>ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti <strong>solo se<\/strong> l&#8217;alea ad essi sottesa \u00e8 <strong>misurabile<\/strong> secondo criteri scientificamente riconosciuti, nonch\u00e9 <strong>esplicitata<\/strong> nel contratto e con presenza di un chiaro accordo tra le parti.<\/p>\n<p>In conclusione, con questa sentenza di portata epocale, la <strong>Suprema Corte di Cassazione <\/strong>stabilisce come, anche per le <strong>Aziende<\/strong>:<\/p>\n<ul>\n<li>Nei contratti <strong>derivati<\/strong> <strong><em>over-the-counter<\/em><\/strong>, stipulati tra <strong>banche<\/strong> e <strong>imprese<\/strong>, il contratto o la scheda prodotto allegati devono <strong>sempre<\/strong> contenere l\u2019esplicitazione del calcolo dell\u2019indice <strong>MTM<\/strong>, i <strong>costi impliciti<\/strong> e gli <strong>scenari probabilistici<\/strong> legati allo strumento finanziario.<\/li>\n<\/ul>\n<p>La <strong>mancata esplicitazione<\/strong> di uno di questi parametri \u00e8 <strong>inconcepibile<\/strong> e si traduce in un <strong>vizio genetico del contratto<\/strong> anche quando la controparte della banca non sia un ente pubblico ma <strong>un\u2019azienda. In questi casi, dunque, il contratto <u>\u00e8 da ritenersi SEMPRE NULLO per indeterminabilit\u00e0 dell\u2019oggetto<\/u><\/strong>.<\/p>\n<p>La recente sentenza <strong>n. 21830\/2021<\/strong> della Prima Sezione Civile della <strong>Suprema Corte di Cassazione<\/strong>, arrivata a distanza di un anno dalla precedente <a href=\"http:\/\/mgr.macoweb.eu\/sentenza-n-8770-2020-cause-di-nullita-dei-contratti-derivati\/\">sentenza della Corte di Cassazione a sezioni unite <strong>n.8770\/2020<\/strong><\/a> che riguardava gli enti locali, non solo conferma la tendenza positiva del panorama giuridico nei confronti degli <strong>investitori che hanno subito perdite illegittime<\/strong> a causa dei derivati, ma afferma come &#8211; anche per quanto riguarda le aziende &#8211; la stipula di un <strong>contratto derivato<\/strong> debba inderogabilmente sottostare a determinati parametri, pena la <strong>nullit\u00e0<\/strong> immediata dello stesso.<\/p>\n<p><strong>HAI STIPULATO CONTRATTI DERIVATI? ECCO COME RECUPERARE:<\/strong><\/p>\n<p>Tutti gli investitori &#8211; siano essi individui, aziende o enti locali &#8211; che hanno subito perdite a seguito della stipula di contratti derivati con le banche italiane possono ora far valere in giudizio la nullit\u00e0 di questi ultimi. Tale punto di arrivo \u00e8 il risultato di un lungo ed articolato dibattito in dottrina e giurisprudenza, consolidato proprio grazie alle sentenze <strong>n.21830\/2021 <\/strong>e <strong>n.8770\/2020 <\/strong>della <strong>Suprema Corte di Cassazione<\/strong>.<\/p>\n<p><strong>Martingale Risk<\/strong> dal 2009 ha assistito migliaia di investitori privati, imprese e centinaia di enti locali nel recupero delle perdite subite su <strong>contratti derivati<\/strong>, con possibilit\u00e0 di valutare la modalit\u00e0 di <strong>pagamento posticipato solo a rimborso realmente ottenuto<\/strong>. \u00a0Ad oggi <strong>Martingale Risk<\/strong> ha gi\u00e0 recuperato pi\u00f9 di <strong>230 milioni di Euro<\/strong> di perdite, con una percentuale di successo pari al <strong>92%<\/strong>.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":25314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,18],"tags":[80,64,82,73,194,66],"class_list":["post-25309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-approfondimenti-derivati","category-news","tag-banche","tag-cassazione","tag-contratti","tag-derivati","tag-news","tag-risarcimento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021 - Martingale<\/title>\n<meta name=\"description\" content=\"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l&#039;alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021 - Martingale\" \/>\n<meta property=\"og:description\" content=\"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l&#039;alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T12:07:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicol\u00f2 Uccellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00f2 Uccellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/\"},\"author\":{\"name\":\"Nicol\u00f2 Uccellini\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"headline\":\"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\\\/2021\",\"datePublished\":\"2021-11-11T12:07:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/\"},\"wordCount\":903,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"keywords\":[\"banche\",\"cassazione\",\"contratti\",\"derivati\",\"news\",\"risarcimento\"],\"articleSection\":[\"Approfondimenti Derivati\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/\",\"name\":\"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\\\/2021 - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"datePublished\":\"2021-11-11T12:07:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"description\":\"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l'alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"width\":1200,\"height\":630,\"caption\":\"Cassazione Derivati Aziende\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/aziende-nuova-cassazione-derivati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\\\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\",\"name\":\"Nicol\u00f2 Uccellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00f2 Uccellini\"},\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021 - Martingale","description":"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l'alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021 - Martingale","og_description":"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l'alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.","og_url":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/","og_site_name":"Martingale","article_published_time":"2021-11-11T12:07:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png","type":"image\/png"}],"author":"Nicol\u00f2 Uccellini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicol\u00f2 Uccellini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#article","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/"},"author":{"name":"Nicol\u00f2 Uccellini","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"headline":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021","datePublished":"2021-11-11T12:07:08+00:00","mainEntityOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/"},"wordCount":903,"commentCount":0,"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png","keywords":["banche","cassazione","contratti","derivati","news","risarcimento"],"articleSection":["Approfondimenti Derivati","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/","url":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/","name":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021 - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png","datePublished":"2021-11-11T12:07:08+00:00","author":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"description":"La decisione finale della Corte si basa sull\u2019assunto che i derivati, espressione di una logica probabilistica, sono per loro natura contratti atipici a cui si applicano le leggi del mercato finanziario. In questo caso - pur restando vero che l\u2019IRS assolve la propria finalit\u00e0 di copertura - esso conserva la caratterizzazione di strumento di gestione del rischio finanziario che qualifica un contratto valido qualora persegua interessi meritevoli di tutela ed abbia una valida causa in concreto. Questi requisiti risultano soddisfatti solo se l'alea ad essi sottesa \u00e8 misurabile secondo criteri scientificamente riconosciuti, nonch\u00e9 esplicitata nel contratto e con presenza di un chiaro accordo tra le parti.","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2021\/11\/1200x630-Copertina-Articoli-Sito-2.png","width":1200,"height":630,"caption":"Cassazione Derivati Aziende"},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/aziende-nuova-cassazione-derivati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"NULLIT\u00c0 CONTRATTI DERIVATI: PER LE AZIENDE \u00c8 PI\u00d9 FACILE RECUPERARE GRAZIE ALLA RECENTE SENTENZA DELLA CORTE DI CASSAZIONE n.21830\/2021"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5","name":"Nicol\u00f2 Uccellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","caption":"Nicol\u00f2 Uccellini"},"url":"https:\/\/sviluppodunp.it\/martingale\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/25309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=25309"}],"version-history":[{"count":0,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/25309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/25314"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=25309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categories?post=25309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/tags?post=25309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}