{"id":27040,"date":"2022-02-28T10:03:01","date_gmt":"2022-02-28T09:03:01","guid":{"rendered":"http:\/\/mgr.macoweb.eu\/?p=27040"},"modified":"2022-02-28T10:03:01","modified_gmt":"2022-02-28T09:03:01","slug":"contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana","status":"publish","type":"post","link":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/","title":{"rendered":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">Ennesimo successo su contratti derivati per <strong>Martingale Risk<\/strong>: abbiamo ottenuto un risarcimento di quasi <strong>mezzo milione di Euro<\/strong> per un\u2019azienda edile della Campania. La vittoria \u00e8 arrivata dopo un procedimento di causa ordinaria di fronte al Tribunale di Bari, che ha dato ragione al nostro cliente. Martingale Risk, azienda di contestazione bancaria leader nel panorama italiano, offre un\u2019<strong>Analisi Preliminare Gratuita<\/strong>, per verificare se e quanto \u00e8 possibile recuperare dalla propria banca. Grazie alla politica di <strong>Zero Costi Anticipati<\/strong>, il cliente non verser\u00e0 alcuna somma iniziale, ma unicamente una percentuale sulle cifre recuperate, a rimborso effettivamente avvenuto.<\/p>\n<h2 style=\"text-align: left;\"><strong>Contratti derivati: il punto della situazione in Italia<\/strong><\/h2>\n<p style=\"text-align: justify;\">In passato, molte aziende hanno stipulato con il proprio istituto di credito contratti derivati, fortemente consigliati dalle stesse banche. Tali contratti, nello specifico i <strong>derivati IRS<\/strong> (Interest rate swap), sono prodotti altamente complessi. Con essi infatti, le parti si scambiamo flussi di denaro di cui uno \u00e8 a tasso fisso, mentre l\u2019altro variabile. Questi strumenti finanziari, venduti come investimenti sicuri, hanno presto rivelato la loro natura speculativa, causando <strong>perdite ingenti<\/strong> e portando molte aziende <strong>sull\u2019orlo del fallimento<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La <strong>Corte di Cassazione<\/strong> e la <strong>Corte di Cassazione a Sezioni Unite<\/strong> si sono espresse negli ultimi anni con le sentenze <strong>n. 21830\/2021<\/strong>\u00a0e<strong> 8770\/2020<\/strong>. Entrambe le Corti affermano che qualora il <strong>contratto derivato<\/strong> non contenga l\u2019esplicitazione dell\u2019indice <em>mark to market<\/em>, i costi impliciti e gli scenari probabilistici legati allo strumento finanziario, questo \u00e8 da ritenersi <strong>sempre nullo<\/strong>, per indeterminabilit\u00e0 dell\u2019oggetto.<\/p>\n<p style=\"text-align: justify;\">Sulla base di questa nuova sentenze favorevole, \u00e8 ora molto pi\u00f9 facile contestare le inadempienze delle banche. Le aziende possono cos\u00ec avviare un contenzioso relativo alla <strong>stipula di contratti derivati<\/strong> e ottenere un <strong>congruo risarcimento<\/strong>.<\/p>\n<h2 style=\"text-align: left;\"><strong>Vittoria in tribunale: quasi mezzo milione di Euro per il nostro cliente<\/strong><\/h2>\n<p style=\"text-align: justify;\">L\u2019azienda in questione si \u00e8 rivolta a noi per verificare la presenza di potenziali irregolarit\u00e0 nel rapporto di contratto derivato stipulato con la propria banca, il quale le aveva causato sostanziose perdite. Grazie al lavoro del nostro team di esperti tecnico legali sono state riconosciute numerose irregolarit\u00e0 in capo all\u2019istituto di credito. Il contratto non conteneva infatti la formula del calcolo matematico dell\u2019indice <em>mark to market<\/em>, e non vi era alcun richiamo a criteri diffusi ed accertati dalla prassi di settore per la definizione della stessa.<\/p>\n<p style=\"text-align: justify;\">Di conseguenza, il contratto non presentava alcuna indicazione relativa alla misura qualitativa e quantitativa dell\u2019alea o dei costi impliciti, come confermato anche dal CTU. Il contratto inoltre non indicava correttamente n\u00e9 gli scenari probabilistici n\u00e9 i costi impliciti applicati, in modo scorretto, dalla banca. Infatti solamente grazie alla presenza della formula di calcolo dell\u2019indice mark to market, degli scenari probabilistici e della misura dei costi relativi alla stipula, \u00e8 possibile esplicitare la misura del rischio finanziario correlato.<\/p>\n<p style=\"text-align: justify;\">La mancanza di tali elementi, come affermato dalle precedenti sentenze della Cassazione, ha portato alla nullit\u00e0 del contratto derivato. Con <a href=\"http:\/\/mgr.macoweb.eu\/wp-content\/uploads\/2021\/11\/Caisp_org.pdf\" target=\"_blank\" rel=\"noopener\"><u>sentenza favorevole<\/u><\/a>, il Tribunale di Bari si \u00e8 dunque espresso condannando la banca a risarcire il nostro cliente della somma di <strong>\u20ac 486.929,01<\/strong>.<\/p>\n<h2 style=\"text-align: left;\"><strong>Hai subito perdite da contratti derivati? Ecco cosa fare<\/strong><\/h2>\n<p style=\"text-align: justify;\">Se anche la tua azienda ha registrato ingenti perdite in seguito alla stipula di un contratto di natura derivata, rivolgiti a <strong>Martingale Risk<\/strong>. Un consulente specializzato ti seguir\u00e0 nella fase di mediazione bonaria con la banca e qualora questa non bastasse, verrai assistito anche durante il contenzioso di fronte all\u2019Arbitro per le Controversie Finanziarie o al Tribunale competente, come successo nel caso approfondito. Martingale Risk mette a disposizione dei propri clienti i nostri migliori avvocati e previa analisi ci facciamo carico anche di tutte le spese legali.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":28181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[78,79,18],"tags":[14,69,80,70,82,72,84,73,17,85,66],"class_list":["post-27040","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-approfondimenti","category-approfondimenti-derivati","category-news","tag-azienda","tag-banca","tag-banche","tag-cliente","tag-contratti","tag-contratto","tag-costi","tag-derivati","tag-martingale-risk","tag-perdite","tag-risarcimento","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale<\/title>\n<meta name=\"description\" content=\"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale\" \/>\n<meta property=\"og:description\" content=\"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T09:03:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicol\u00f2 Uccellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00f2 Uccellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/\"},\"author\":{\"name\":\"Nicol\u00f2 Uccellini\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"headline\":\"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA\",\"datePublished\":\"2022-02-28T09:03:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/\"},\"wordCount\":775,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"keywords\":[\"azienda\",\"banca\",\"banche\",\"cliente\",\"contratti\",\"contratto\",\"costi\",\"derivati\",\"martingale risk\",\"perdite\",\"risarcimento\"],\"articleSection\":[\"Approfondimenti\",\"Approfondimenti Derivati\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/\",\"name\":\"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"datePublished\":\"2022-02-28T09:03:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"description\":\"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"width\":1200,\"height\":630,\"caption\":\"Azienda Edile\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\",\"name\":\"Nicol\u00f2 Uccellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00f2 Uccellini\"},\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale","description":"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale","og_description":"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari","og_url":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/","og_site_name":"Martingale","article_published_time":"2022-02-28T09:03:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png","type":"image\/png"}],"author":"Nicol\u00f2 Uccellini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicol\u00f2 Uccellini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#article","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/"},"author":{"name":"Nicol\u00f2 Uccellini","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"headline":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA","datePublished":"2022-02-28T09:03:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/"},"wordCount":775,"commentCount":0,"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png","keywords":["azienda","banca","banche","cliente","contratti","contratto","costi","derivati","martingale risk","perdite","risarcimento"],"articleSection":["Approfondimenti","Approfondimenti Derivati","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/","url":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/","name":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png","datePublished":"2022-02-28T09:03:01+00:00","author":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"description":"Ennesimo successo su contratti derivati: ottenuto risarcimento di quasi mezzo milione di Euro per azienda edile campana al Tribunale di Bari","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/02\/1200x630-Copertina-Articoli-Sito-3.png","width":1200,"height":630,"caption":"Azienda Edile"},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-risarcimento-48692901-sentenza-favorevole-azienda-edile-campana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"CONTRATTI DERIVATI: RISARCIMENTO DI \u20ac 486.929,01 CON SENTENZA FAVOREVOLE PER UN\u2019AZIENDA EDILE CAMPANA"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5","name":"Nicol\u00f2 Uccellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","caption":"Nicol\u00f2 Uccellini"},"url":"https:\/\/sviluppodunp.it\/martingale\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/27040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=27040"}],"version-history":[{"count":0,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/27040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/28181"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=27040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categories?post=27040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/tags?post=27040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}