{"id":29978,"date":"2022-12-14T12:18:20","date_gmt":"2022-12-14T11:18:20","guid":{"rendered":"http:\/\/mgr.macoweb.eu\/?p=29978"},"modified":"2022-12-14T12:18:20","modified_gmt":"2022-12-14T11:18:20","slug":"contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero","status":"publish","type":"post","link":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/","title":{"rendered":"Contratti derivati: con la nuova giurisprudenza aumentano le possibilit\u00e0 di recupero"},"content":{"rendered":"<p style=\"text-align: justify;\">Con oltre 13 anni di esperienza, <strong>Martingale Risk<\/strong> \u00e8 una societ\u00e0 di\u202fprimo piano in Italia che unisce analisti finanziari ed avvocati specializzati in contenzioso finanziario. Essa \u00e8 \u202fMembro Certificato della Top Legal Directory\u202fe recentemente \u00e8 stata inserita tra le\u202fprime 200 aziende italiane\u202fdei Campioni della Crescita per il triennio 2018-2021, secondo la classifica stilata da Repubblica insieme all&#8217;Istituto Tedesco Qualit\u00e0 e Finanza. Inoltre \u00e8 stata\u202fcertificata Leader della Crescita 2019 da IlSole24Ore. Lo studio professionale offre un\u2019<strong>Analisi Preliminare Gratuita<\/strong> del caso per coloro che hanno subito perdite a causa di comportamenti scorretti della propria banca. Martingale Risk segue la politica degli <strong>Zero Costi Anticipati<\/strong> e si fa carico delle eventuali spese legali e peritali. La societ\u00e0 di consulenza finanziaria si assume quindi il rischio dell\u2019iniziativa, qualora ricorrano i presupposti. Martingale Risk pu\u00f2 oggi supportare le societ\u00e0 basandosi sulla recente giurisprudenza,\u00a0 il nostro scopo \u00e8 quindi il recupero delle perdite illegittime subite dai clienti a causa della propria banca sui contratti derivati. \u00a0<\/p>\n<h2>\u00a0<\/h2>\n<h2>La nuova giurisprudenza della Cassazione aumenta le possibilit\u00e0 di recupero sui contratti derivati<\/h2>\n<p style=\"text-align: justify;\">Dopo la <strong><a href=\"https:\/\/www.adnkronos.com\/Archivio\/immediapress\/economia-finanza\/martingale-risk-la-cassazione-al-fianco-di-imprese-ed-enti-locali-traditi-dallacquisto-di-derivati_5EbHRll1z63JjNHUjmMmlO\" target=\"_blank\" rel=\"noopener\">Sentenza della Corte di Cassazione<\/a> a sezioni unite n. 8770\/2020<\/strong> che riguardava gli enti locali, la recente <strong>Sentenza n.21830\/2021 della Prima Sezione Civile della Suprema Corte di Cassazione<\/strong>, tutela i diritti di tutti coloro che hanno subito perdite illegittime da derivati, anche qualora si tratti di un\u2019azienda. Con quest\u2019ultima sentenza sar\u00e0 possibile citare in causa le banche che hanno illegittimamente causato perdite alle aziende sui derivati. Infatti si potr\u00e0 addirittura ottenere la nullit\u00e0 dei contratti stessi.\u202f\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Nonostante siano molto diffusi, i derivati sono strumenti finanziari complessi, speculativi e molto rischiosi. Tra i vari derivati vi sono quelli venduti come \u201cvanilla\u201d, come gli Interest Rate Swap (IRS). Quest&#8217;ultimi permettono a due controparti di scambiare flussi di denaro per un determinato lasso di tempo. Quindi questo tipo di contratti viene proposto dalle banche come adatto alla copertura del rischio dei rialzi dei tassi. Nella pratica per\u00f2 non \u00e8 stato cos\u00ec come testimoniano le ingenti perdite di innumerevoli aziende italiane. \u00a0<\/p>\n<h2>\u00a0<\/h2>\n<h2 style=\"text-align: justify;\"><strong>Quali criticit\u00e0 sono contestabili in ambito di contratti derivati?<\/strong><\/h2>\n<p style=\"text-align: justify;\">Oggi, grazie alla nuova giurisprudenza favorevole della Cassazione, si pu\u00f2 facilmente <strong>agire per recuperare le somme perdute sui derivati<\/strong>. Una banca nazionale ha impugnato una Sentenza della Corte d\u2019Appello di Milano. Quest\u2019ultima si era espressa nel 2018 a favore di un\u2019azienda agricola, dichiarando la nullit\u00e0 del contratto Interest Rate Swap (IRS) stipulato nel 2011 con la banca stessa. I motivi di nullit\u00e0 si basavano sulla presenza della contabilizzazione illegittima dell\u2019indice mark-to-market (MTM), sia per il suo valore, sia per i criteri di calcolo impiegati per determinarlo. Il contratto derivato era stato stipulato come copertura dal rischio di un futuro rialzo dei tassi di interesse, quest\u2019ultimo si \u00e8 invece rivelato sfavorevole per il cliente. La banca ha tentato di difendersi affermando che l\u2019indice mark-to-market \u00e8 un valore teorico e virtuale, e che quindi non inciderebbe sulle prestazioni di ciascuna parte. Tuttavia l\u2019indice non risulta determinato o determinabile dalle informazioni del contratto.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">La Corte di Cassazione stabilisce con la propria decisione finale un orientamento sui contratti derivati OTC stipulati tra banche e imprese. Il contratto o la scheda prodotto allegata devono ora sempre contenere l\u2019esplicitazione del calcolo dell\u2019indice MTM, i costi impliciti e gli scenari probabilistici relativi allo strumento finanziario, pena nullit\u00e0 del contratto stesso. Inoltre anche se vi \u00e8 incoerenza tra pagamenti del derivato e del debito sottostante o\u202fmancanza di un contratto quadro validamente perfezionato, il contratto \u00e8 da ritenersi nullo. La mancata esplicitazione di uno di questi elementi \u00e8 inconcepibile e si traduce in un vizio del contratto. Questo vale sia che la controparte della banca sia un ente pubblico sia che sia un\u2019azienda. In questi casi il contratto risulta sempre <strong>nullo per indeterminabilit\u00e0 dell\u2019oggetto<\/strong>.\u00a0<\/p>\n<h2>\u00a0<\/h2>\n<h2>Nuovo caso di successo al Tribunale di Milano su contratti derivati per un&#8217;azienda nostra cliente<\/h2>\n<p style=\"text-align: justify;\">Il team di ingegneria finanziaria di Martingale Risk \u00e8 stato il primo in Italia a dimostrare in modo scientifico queste violazioni, dinnanzi ai tribunali Italiani. E&#8217; questo il motivo per cui moltissime aziende si sono affidate alla societ\u00e0 di consulenza finanziaria per recuperare le perdite subite sui derivati. Tra le societ\u00e0 trattate vi \u00e8 anche un\u2019importante azienda campana distributrice di carburante. Quest\u2019ultima si \u00e8 rivolta a Martingale Risk per analizzare una decina di contratti derivati stipulati con la propria banca. Gli analisti finanziari della societ\u00e0 di consulenza hanno rilevato l\u2019assenza del metodo di calcolo dell\u2019indice MTM. L\u2019azienda campana ha citato cos\u00ec in causa la banca di fronte al Tribunale di Milano. Quest\u2019ultimo ha convenuto con le deduzioni di Martingale Risk e ha dichiarato nulli i contratti per indeterminabilit\u00e0 dell\u2019oggetto. La parte lesa ha potuto cos\u00ec ottenere il\u00a0<strong>risarcimento di \u20ac 1.888.048,60<\/strong>. Ci\u00f2 dimostra che grazie alla nuova giurisprudenza tutte le aziende che hanno subito perdite in seguito alla stipula di contratti derivati hanno ora concrete possibilit\u00e0 di recupero.\u00a0 \u00a0<\/p>\n<h2>Hai subito perdite su contratti derivati? Ottieni il giusto recupero con Martingale Risk\u00a0<\/h2>\n<p><a href=\"https:\/\/sviluppodunp.it\/martingale\/analisi-perdite-da-derivati\/\">contattaci cliccando qui\u00a0<\/a><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sviluppodunp.it\/martingale\/analisi-perdite-da-derivati\/\"><br \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-1024x577.png\" alt=\"\" srcset=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-200x113.png 200w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-300x169.png 300w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-400x225.png 400w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-600x338.png 600w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-768x433.png 768w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-800x451.png 800w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-1024x577.png 1024w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-1200x676.png 1200w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1-1536x865.png 1536w, https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/Casi-di-Successo-Censurati-Sito-1.png 1640w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con oltre 13 anni di esperienza, Martingale Risk \u00e8 una  [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":29981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[78,79,18],"tags":[21,69,82,72,73,17,85,35],"class_list":["post-29978","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-approfondimenti","category-approfondimenti-derivati","category-news","tag-aziende","tag-banca","tag-contratti","tag-contratto","tag-derivati","tag-martingale-risk","tag-perdite","tag-societa","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contratti derivati: la nuova giurisprudenza per il recupero<\/title>\n<meta name=\"description\" content=\"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contratti derivati: la nuova giurisprudenza per il recupero\" \/>\n<meta property=\"og:description\" content=\"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T11:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicol\u00f2 Uccellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00f2 Uccellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/\"},\"author\":{\"name\":\"Nicol\u00f2 Uccellini\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"headline\":\"Contratti derivati: con la nuova giurisprudenza aumentano le possibilit\u00e0 di recupero\",\"datePublished\":\"2022-12-14T11:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/\"},\"wordCount\":835,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"keywords\":[\"aziende\",\"banca\",\"contratti\",\"contratto\",\"derivati\",\"martingale risk\",\"perdite\",\"societ\u00e0\"],\"articleSection\":[\"Approfondimenti\",\"Approfondimenti Derivati\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/\",\"name\":\"Contratti derivati: la nuova giurisprudenza per il recupero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"datePublished\":\"2022-12-14T11:18:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"description\":\"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/1200x630-Copertina-Articoli-Sito-3.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contratti derivati: con la nuova giurisprudenza aumentano le possibilit\u00e0 di recupero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\",\"name\":\"Nicol\u00f2 Uccellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00f2 Uccellini\"},\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contratti derivati: la nuova giurisprudenza per il recupero","description":"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Contratti derivati: la nuova giurisprudenza per il recupero","og_description":"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati","og_url":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/","og_site_name":"Martingale","article_published_time":"2022-12-14T11:18:20+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png","type":"image\/png"}],"author":"Nicol\u00f2 Uccellini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicol\u00f2 Uccellini","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#article","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/"},"author":{"name":"Nicol\u00f2 Uccellini","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"headline":"Contratti derivati: con la nuova giurisprudenza aumentano le possibilit\u00e0 di recupero","datePublished":"2022-12-14T11:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/"},"wordCount":835,"commentCount":0,"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png","keywords":["aziende","banca","contratti","contratto","derivati","martingale risk","perdite","societ\u00e0"],"articleSection":["Approfondimenti","Approfondimenti Derivati","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/","url":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/","name":"Contratti derivati: la nuova giurisprudenza per il recupero","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png","datePublished":"2022-12-14T11:18:20+00:00","author":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"description":"Con la nuova giurisprudenza della Cassazione \u00e8 possibile per le aziende ottenere il recupero di perdite subite su contratti derivati","breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2022\/12\/1200x630-Copertina-Articoli-Sito-3.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/contratti-derivati-nuova-giurisprudenza-solide-possibilita-di-recupero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"Contratti derivati: con la nuova giurisprudenza aumentano le possibilit\u00e0 di recupero"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5","name":"Nicol\u00f2 Uccellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","caption":"Nicol\u00f2 Uccellini"},"url":"https:\/\/sviluppodunp.it\/martingale\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/29978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=29978"}],"version-history":[{"count":0,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/29978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/29981"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=29978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categories?post=29978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/tags?post=29978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}