{"id":37713,"date":"2025-06-25T10:43:21","date_gmt":"2025-06-25T08:43:21","guid":{"rendered":"https:\/\/martingalerisk.it\/?p=37713"},"modified":"2025-06-25T10:43:21","modified_gmt":"2025-06-25T08:43:21","slug":"cartello-smaltimento-veicoli-a-fine-vita-cose","status":"publish","type":"post","link":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/","title":{"rendered":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: justify;\" data-start=\"587\" data-end=\"893\"><strong data-start=\"587\" data-end=\"644\">Il cartello sullo smaltimento dei veicoli a fine vita<\/strong> \u00e8 una delle pi\u00f9 gravi violazioni della normativa antitrust degli ultimi anni. Riguarda grandi case automobilistiche europee che avrebbero manipolato il mercato del riciclo e demolizione degli autoveicoli, danneggiando imprese, ambiente e cittadini.<\/p>\n<p style=\"text-align: justify;\" data-start=\"895\" data-end=\"1078\">In questo approfondimento, analizziamo i fatti accaduti, le implicazioni legali e perch\u00e9 \u00e8 fondamentale rivolgersi a uno studio come <strong data-start=\"1028\" data-end=\"1047\">Martingale Risk<\/strong> per tutelare i propri diritti.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"1085\" data-end=\"1160\">Cosa si intende per cartello sullo smaltimento dei veicoli a fine vita?<\/h3>\n<p style=\"text-align: justify;\" data-start=\"1162\" data-end=\"1413\">Il <strong data-start=\"1165\" data-end=\"1209\">cartello smaltimento veicoli a fine vita<\/strong> \u00e8 un\u2019intesa illecita tra costruttori automobilistici finalizzata a <strong data-start=\"1277\" data-end=\"1349\">controllare i costi del trattamento degli ELV (End of Life Vehicles)<\/strong>, ovvero i veicoli giunti al termine del loro ciclo di utilizzo.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1415\" data-end=\"1429\">Nel dettaglio:<\/p>\n<ul style=\"text-align: justify;\" data-start=\"1431\" data-end=\"1815\">\n<li data-start=\"1431\" data-end=\"1565\">\n<p data-start=\"1433\" data-end=\"1565\">Aziende come <strong data-start=\"1446\" data-end=\"1482\">Volkswagen, Stellantis e Renault<\/strong> avrebbero stabilito accordi per <strong data-start=\"1515\" data-end=\"1564\">non pagare i centri di raccolta e trattamento<\/strong>;<\/p>\n<\/li>\n<li data-start=\"1566\" data-end=\"1662\">\n<p data-start=\"1568\" data-end=\"1662\">Hanno scambiato <strong data-start=\"1584\" data-end=\"1610\">informazioni riservate<\/strong> sui costi di gestione e sulle politiche ambientali;<\/p>\n<\/li>\n<li data-start=\"1663\" data-end=\"1815\">\n<p data-start=\"1665\" data-end=\"1815\">L\u2019obiettivo era evitare spese legate al riciclo dei materiali, <strong data-start=\"1728\" data-end=\"1771\">violando la normativa sulla concorrenza<\/strong> e rallentando la sostenibilit\u00e0 del settore.<\/p>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\" data-start=\"1817\" data-end=\"1976\">Questa condotta ha avuto effetti distorsivi su tutto il mercato europeo e ha portato la Commissione UE a infliggere <a href=\"https:\/\/finanza.repubblica.it\/News\/2025\/04\/01\/ue_multe_a_15_produttori_di_auto_per_cartello_su_riciclo_stellantis_paga_75_milioni-193\/\"><strong data-start=\"1933\" data-end=\"1975\">sanzioni per oltre 450 milioni di euro<\/strong><\/a>.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"1983\" data-end=\"2056\">Perch\u00e9 il cartello sullo smaltimento dei veicoli \u00e8 un problema serio?<\/h3>\n<h4 style=\"text-align: justify;\" data-start=\"2058\" data-end=\"2096\">1. <strong data-start=\"2066\" data-end=\"2096\">Violazione delle regole UE<\/strong><\/h4>\n<p style=\"text-align: justify;\" data-start=\"2097\" data-end=\"2250\">Le aziende coinvolte hanno infranto l\u2019articolo 101 del Trattato sul Funzionamento dell\u2019Unione Europea, che vieta le intese restrittive della concorrenza.<\/p>\n<h4 style=\"text-align: justify;\" data-start=\"2252\" data-end=\"2293\">2. <strong data-start=\"2260\" data-end=\"2293\">Danno ambientale ed economico<\/strong><\/h4>\n<p style=\"text-align: justify;\" data-start=\"2294\" data-end=\"2464\">Il cartello ha <strong data-start=\"2309\" data-end=\"2355\">limitato l\u2019utilizzo di materiali riciclati<\/strong>, aumentato i costi per gli operatori virtuosi e creato un vantaggio sleale per chi non rispettava le regole.<\/p>\n<h4 style=\"text-align: justify;\" data-start=\"2466\" data-end=\"2508\">3. <strong data-start=\"2474\" data-end=\"2508\">Impatto su imprese e cittadini<\/strong><\/h4>\n<p style=\"text-align: justify;\" data-start=\"2509\" data-end=\"2699\">Autodemolitori, aziende di gestione rifiuti e persino le pubbliche amministrazioni sono state colpite da questa intesa, con <strong data-start=\"2633\" data-end=\"2698\">mancati guadagni, aumenti di costi e perdita di competitivit\u00e0<\/strong>.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"2706\" data-end=\"2784\">Chi pu\u00f2 agire legalmente contro il cartello sullo smaltimento dei veicoli?<\/h3>\n<p style=\"text-align: justify;\" data-start=\"2786\" data-end=\"2853\">Tutti i soggetti che hanno subito un danno economico possono agire:<\/p>\n<ul style=\"text-align: justify;\" data-start=\"2855\" data-end=\"3149\">\n<li data-start=\"2855\" data-end=\"2930\">\n<p data-start=\"2857\" data-end=\"2930\"><strong data-start=\"2857\" data-end=\"2888\">Autodemolitori e centri ELV<\/strong> che non hanno ricevuto i compensi dovuti;<\/p>\n<\/li>\n<li data-start=\"2931\" data-end=\"2994\">\n<p data-start=\"2933\" data-end=\"2994\"><strong data-start=\"2933\" data-end=\"2972\">Operatori della filiera del riciclo<\/strong> e aziende ambientali;<\/p>\n<\/li>\n<li data-start=\"3072\" data-end=\"3149\">\n<p data-start=\"3074\" data-end=\"3149\"><strong data-start=\"3074\" data-end=\"3103\">Associazioni di categoria<\/strong> e consumatori penalizzati da costi indiretti.<\/p>\n<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\" data-start=\"3156\" data-end=\"3203\">Come ottenere giustizia con Martingale Risk<\/h3>\n<p style=\"text-align: justify;\" data-start=\"3205\" data-end=\"3398\">Martingale Risk \u00e8 il partner legale ideale per chi vuole agire contro il <strong data-start=\"3278\" data-end=\"3322\">cartello smaltimento veicoli a fine vita<\/strong>, grazie a un approccio legale integrato, efficace e orientato al risultato.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3400\" data-end=\"3409\">Offriamo:<\/p>\n<ul style=\"text-align: justify;\" data-start=\"3411\" data-end=\"3745\">\n<li data-start=\"3411\" data-end=\"3487\">\n<p data-start=\"3413\" data-end=\"3487\"><strong data-start=\"3413\" data-end=\"3444\">Consulenza legale su misura<\/strong> per imprese, enti e operatori del settore;<\/p>\n<\/li>\n<li data-start=\"3488\" data-end=\"3568\">\n<p data-start=\"3490\" data-end=\"3568\"><strong data-start=\"3490\" data-end=\"3526\">Assistenza nel calcolo del danno<\/strong> subito e nella richiesta di risarcimento;<\/p>\n<\/li>\n<li data-start=\"3569\" data-end=\"3655\">\n<p data-start=\"3571\" data-end=\"3655\"><strong data-start=\"3571\" data-end=\"3623\">Supporto in procedimenti civili e amministrativi<\/strong> a livello nazionale ed europeo: copriamo interamente i costi di perizia e di causa<\/p>\n<\/li>\n<li data-start=\"3656\" data-end=\"3745\">\n<p data-start=\"3658\" data-end=\"3745\"><strong>Nessun costo iniziale<\/strong>: il pagamento \u00e8 solo in caso di esito positivo, con una percentuale del risarcimento recuperato.<\/p>\n<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\" data-start=\"3752\" data-end=\"3767\">Conclusioni<\/h3>\n<p style=\"text-align: justify;\" data-start=\"3769\" data-end=\"4015\">Il <strong data-start=\"3772\" data-end=\"3826\">cartello sullo smaltimento dei veicoli a fine vita<\/strong> rappresenta un grave ostacolo alla concorrenza, alla sostenibilit\u00e0 e ai diritti degli operatori onesti. Ma \u00e8 anche un\u2019opportunit\u00e0 per far valere le proprie ragioni attraverso la giustizia.<\/p>\n<p style=\"text-align: justify;\" data-start=\"4017\" data-end=\"4197\">\u00a0Se ritieni di essere stato danneggiato o vuoi saperne di pi\u00f9, <a href=\"https:\/\/sviluppodunp.it\/martingale\/contatti\/\"><strong data-start=\"4082\" data-end=\"4110\">contatta Martingale Risk<\/strong><\/a>: siamo pronti a difendere i tuoi diritti e a costruire insieme una strategia vincente. <a href=\"https:\/\/sviluppodunp.it\/martingale\/mini-approfondimento\/cartello-sullo-smaltimento-dei-veicoli-a-fine-vita\/\">Clicca qui<\/a> per maggiori informazioni.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"4204\" data-end=\"4254\">\ud83d\udcde Contattaci ora per una valutazione gratuita<\/h3>\n<blockquote data-start=\"4256\" data-end=\"4343\">\n<p style=\"text-align: justify;\" data-start=\"4258\" data-end=\"4343\">Difendi la tua impresa. Proteggi l\u2019ambiente. Scegli la competenza di Martingale Risk.<\/p>\n<\/blockquote>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":37717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[78,18],"tags":[],"class_list":["post-37713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-approfondimenti","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/\" \/>\n<meta property=\"og:site_name\" content=\"Martingale\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-25T08:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicol\u00f2 Uccellini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00f2 Uccellini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/\"},\"author\":{\"name\":\"Nicol\u00f2 Uccellini\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"headline\":\"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia\",\"datePublished\":\"2025-06-25T08:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/\"},\"wordCount\":1160,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"articleSection\":[\"Approfondimenti\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/\",\"name\":\"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"datePublished\":\"2025-06-25T08:43:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"contentUrl\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1200x630-Copertina-Articoli-Sito-2.png\",\"width\":1200,\"height\":630,\"caption\":\"cartello smaltimento veicoli a fine vita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/cartello-smaltimento-veicoli-a-fine-vita-cose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#website\",\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/\",\"name\":\"Martingale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/#\\\/schema\\\/person\\\/fe9665201bdceeb3f1efb0d8c51c70d5\",\"name\":\"Nicol\u00f2 Uccellini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00f2 Uccellini\"},\"url\":\"https:\\\/\\\/sviluppodunp.it\\\/martingale\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale","og_url":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/","og_site_name":"Martingale","article_published_time":"2025-06-25T08:43:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png","type":"image\/png"}],"author":"Nicol\u00f2 Uccellini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nicol\u00f2 Uccellini","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#article","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/"},"author":{"name":"Nicol\u00f2 Uccellini","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"headline":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia","datePublished":"2025-06-25T08:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/"},"wordCount":1160,"commentCount":0,"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png","articleSection":["Approfondimenti","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/","url":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/","name":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia - Martingale","isPartOf":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#primaryimage"},"image":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#primaryimage"},"thumbnailUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png","datePublished":"2025-06-25T08:43:21+00:00","author":{"@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5"},"breadcrumb":{"@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#primaryimage","url":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png","contentUrl":"https:\/\/sviluppodunp.it\/martingale\/wp-content\/uploads\/2025\/06\/1200x630-Copertina-Articoli-Sito-2.png","width":1200,"height":630,"caption":"cartello smaltimento veicoli a fine vita"},{"@type":"BreadcrumbList","@id":"https:\/\/sviluppodunp.it\/martingale\/cartello-smaltimento-veicoli-a-fine-vita-cose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sviluppodunp.it\/martingale\/"},{"@type":"ListItem","position":2,"name":"Cartello smaltimento veicoli a fine vita: cos\u2019\u00e8 successo e come ottenere giustizia"}]},{"@type":"WebSite","@id":"https:\/\/sviluppodunp.it\/martingale\/#website","url":"https:\/\/sviluppodunp.it\/martingale\/","name":"Martingale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sviluppodunp.it\/martingale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/sviluppodunp.it\/martingale\/#\/schema\/person\/fe9665201bdceeb3f1efb0d8c51c70d5","name":"Nicol\u00f2 Uccellini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/595b07e70e3aa809d4fa0672c6993ec5ae4894bebd7e3a9b1f0bbf80378dcae8?s=96&d=mm&r=g","caption":"Nicol\u00f2 Uccellini"},"url":"https:\/\/sviluppodunp.it\/martingale\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/37713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/comments?post=37713"}],"version-history":[{"count":0,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/posts\/37713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media\/37717"}],"wp:attachment":[{"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/media?parent=37713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/categories?post=37713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sviluppodunp.it\/martingale\/wp-json\/wp\/v2\/tags?post=37713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}